{"id":14000,"date":"2009-10-13T14:57:26","date_gmt":"2009-10-13T18:57:26","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=14000"},"modified":"2009-10-13T14:57:26","modified_gmt":"2009-10-13T18:57:26","slug":"joao-pedro-correa-do-kart-mirim-da-dicas-de-velocidade","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/joao-pedro-correa-do-kart-mirim-da-dicas-de-velocidade\/14000","title":{"rendered":"Jo\u00e3o Pedro Correa do Kart MIRIM d\u00e1 dicas de velocidade"},"content":{"rendered":"<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/kart1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-14001\" title=\"kart\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/kart1-249x187.jpg\" alt=\"kart\" width=\"249\" height=\"187\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/kart1-249x187.jpg 249w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/kart1-250x187.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/kart1.jpg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/kart1-150x113.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/kart1-265x198.jpg 265w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/kart1-149x112.jpg 149w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/a>Com apenas 8 anos, Jo\u00e3o Pedro Correa compete na Copa S\u00e3o Paulo de Kart Granja Viana. H\u00e1 2 anos, competindo profissionalmente, o garoto coleciona trof\u00e9us e fala da paix\u00e3o pelo o esporte com alma de campe\u00e3o.\u00a0Acelerar nas pistas \u00e9 sem d\u00favida o sonho de muitas crian\u00e7as e h\u00e1 tempos deixou de ser um privil\u00e9gio apenas dos adultos. Seja por hobby, como amador ou profissional \u00e9 um esporte que estimula os pequenos a encarar os desafios. Fora das pistas Jo\u00e3o Pedro coleciona dicas de pilotos como Felipe Massa e Rubens Barrichelo, ambos ex-kartistas.<\/p>\n<p>Para iniciar no Kart a crian\u00e7a precisa ter entre 6 e 12 anos e altura m\u00ednima de 1,18cm e m\u00e1xima de 1,45 cm. No in\u00edcio os pequenos devem buscar um kart\u00f3dromo que incentive aulas te\u00f3ricas e pr\u00e1ticas.<\/p>\n<p>Jo\u00e3o Pedro Correa, diz que a primeira li\u00e7\u00e3o a aprender \u00e9 sobre a hist\u00f3ria do kart e a sinaliza\u00e7\u00e3o e depois t\u00e9cnicas de pilotagem. &#8220;Eu aprendi como frear o carro, como virar na curva e ultrapassar tamb\u00e9m. Al\u00e9m disso, aprendi que correr s\u00f3 \u00e9 bom na pista. Na rua n\u00e3o pode correr, tem que respeitar o farol&#8221;, conta.<\/p>\n<p>Entender como funciona o motor \u00e9 outra dica muito importante para se manter entre os primeiros. &#8220;O Pujol (Alexandre Pujol, assistente t\u00e9cnico) me explica sobre o motor, assim fica mais f\u00e1cil para entender o que devo fazer na corrida&#8221;, refor\u00e7a o pequeno.<\/p>\n<p>Outra dica de JP, como \u00e9 chamado, \u00e9 sobre equipamentos de seguran\u00e7a. &#8220;Para me proteger uso capacete, macac\u00e3o e todos equipamentos. J\u00e1 bati uma vez, mas n\u00e3o machuquei muito, s\u00f3 um pouco e a ambul\u00e2ncia me ajudou. S\u00f3 n\u00e3o machuquei mais porque usei tudo direitinho&#8221;, explica.<\/p>\n<p>Tanta paix\u00e3o pelo esporte n\u00e3o diminui a empolga\u00e7\u00e3o de Jo\u00e3o Pedro pelos estudos, brincadeiras com os amigos e o carinho pelos animais de estima\u00e7\u00e3o. &#8220;Gosto muito de estudar, acho importante ir \u00e0 escola. Adoro jogos eletr\u00f4nicos e coleciono figurinhas do Gogo\u00b4S tamb\u00e9m. Tenho dois gatos e uma cachorrinha, brinco com eles todos os dias&#8221;, conclui o jovem.<\/p>\n<p>Jo\u00e3o Pedro Correa treina no Kart\u00f3dromo Internacional da Granja Viana http:\/\/www.kartodromogranjaviana.com.br<\/p>\n<p>Sobre Jo\u00e3o Pedro Correa:<\/p>\n<p>Jo\u00e3o Pedro Correa, de 8 anos de idade compete pela categoria mirim de Kart h\u00e1 2 anos. Atualmente JP como \u00e9 chamado, \u00e9 o l\u00edder da Copa S\u00e3o Paulo de Kart da Granja Viana. O campeonato \u00e9 reconhecido pela CBA &#8211; Confedera\u00e7\u00e3o Brasileira de Automobilismo &#8211; e pela CNK &#8211; Confedera\u00e7\u00e3o Nacional de Kart. Simultaneamente participa do Campeonato Paulista de Kart no aut\u00f3dromo de Interlagos e Campeonato Brasileiro. Tanta dedica\u00e7\u00e3o \u00e0 velocidade lhe rendeu o t\u00edtulo do Torneio Dolly Guaran\u00e1 em 2008 e a 11\u00ba posi\u00e7\u00e3o no Ranking nacional de pilotos, que compreende mais de 50 em todo o Brasil. Como patrocinador tem o apoio do Grupo Blinder e assessoria t\u00e9cnica de Alexandre Pujol.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com apenas 8 anos, Jo\u00e3o Pedro Correa compete na Copa S\u00e3o Paulo de Kart Granja Viana. H\u00e1 2 anos, competindo profissionalmente, o garoto coleciona trof\u00e9us e fala da paix\u00e3o pelo o esporte com alma de campe\u00e3o.\u00a0Acelerar nas pistas \u00e9 sem d\u00favida o sonho de muitas crian\u00e7as e h\u00e1 tempos deixou de ser um privil\u00e9gio apenas [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-14000","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"has-post-thumbnail","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=14000"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14000\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=14000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=14000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=14000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}