{"id":13991,"date":"2009-10-13T14:49:03","date_gmt":"2009-10-13T18:49:03","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13991"},"modified":"2009-10-13T14:49:03","modified_gmt":"2009-10-13T18:49:03","slug":"marcos-vianna-fala-das-tendencias-de-cabelos-para-o-verao-2010","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/marcos-vianna-fala-das-tendencias-de-cabelos-para-o-verao-2010\/13991","title":{"rendered":"Marcos Vianna fala das tend\u00eancias de cabelos para o ver\u00e3o 2010"},"content":{"rendered":"<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/viana.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-13992\" title=\"viana\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/viana-249x187.jpg\" alt=\"viana\" width=\"249\" height=\"187\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/viana-249x187.jpg 249w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/viana-250x187.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/viana.jpg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/viana-150x113.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/viana-265x198.jpg 265w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/viana-149x112.jpg 149w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/a>Atuando em beleza h\u00e1 mais de duas d\u00e9cadas, o paulistano Marcos Vianna pesquisa e analisa os movimentos que ditam a moda nos cabelos e como as novidades s\u00e3o assimiladas pela mulher brasileira. &#8220;Cabelos longos como as brasileiras gostam s\u00e3o uma marca registrada e fazem o charme; dificilmente em outros pa\u00edses vemos tamanha &#8220;responsabilidade&#8221; da beleza sobre um item como s\u00e3o os cabelos aqui no Brasil, explica Vianna.<\/p>\n<p>E o que ser\u00e1 moda para esta mulher t\u00e3o vaidosa de seus cabelos? Marcos diz: &#8220;A tend\u00eancia de corte de cabelo 2010 \u00e9 o cabelo quase que inteiro, com muita textura nas pontas para ganhar leveza, movimento e um \u00f3timo caimento para qualquer tipo de penteado. Franjas e frentes muito texturizadas valorizar\u00e3o ainda mais o rosto. Se preferir uma franja lateral bem texturizada para melhor caimento, ser\u00e1 muito legal! Caso n\u00e3o queira uma franja curta, a franja longa \u00e9 bem vinda, picotada e fatiada na altura do nariz, boca ou queixo para baixo. \u00c9 a mais democr\u00e1tica das franjas, sendo que pode-se jogar para qualquer lado ou deix\u00e1-la dividida ao meio, simplesmente, sempre respeitando os estudos do visagismo&#8221;, refor\u00e7a.<\/p>\n<p>E por que cabelos t\u00e3o compridos? Segundo o hairstylist, cabelos compridos d\u00e3o mais op\u00e7\u00f5es de penteados. &#8220;A tend\u00eancia dos penteados s\u00e3o rabos de cavalos ou semipresos para o ver\u00e3o 2010 que refrescam muito mais o dia-dia. O importante \u00e9 ter os fios com um caimento despojado e mais natural poss\u00edvel, seja o penteado preso ou semipreso alto, m\u00e9dio ou baixo. O rabo de cavalo, f\u00e1cil de fazer, sempre d\u00e1 um aspecto mais sofisticado e charmoso, variando assim o visual e o look do cabelo solto. O penteado preso alto deixa o visual proporcionalmente mais alto, o penteado preso m\u00e9dio oferece mais praticidade e o penteado preso baixo d\u00e1 um ar rom\u00e2ntico, principalmente se agregar tran\u00e7as. Lembrar sempre da adequa\u00e7\u00e3o do visual: roupa, cabelo e maquiagem no contexto do evento ou do cotidiano&#8221;, explica.<\/p>\n<p>E para quem n\u00e3o gosta de ficar com os fios presos em rabo de cavalo mas sofre com o calor? Marcos Vianna sugere como op\u00e7\u00e3o o semipreso com alguns fios caindo pelo rosto, valorizando o cacheado, f\u00e1cil de fazer. Marcos explica que &#8220;Usando da criatividade, \u00e9 poss\u00edvel fazer penteados lindos, para o dia-dia ou qualquer evento. Pode-se compor tamb\u00e9m com tran\u00e7as. Outra op\u00e7\u00e3o de penteados f\u00e1ceis e pr\u00e1ticos de fazer s\u00e3o os de efeito molhado, utilizando gel, pomadas e ou sprays, que tem um aspecto muito elegante, valorizando ainda mais os acess\u00f3rios para cabelos, brincos e a maquiagem dever\u00e1 ser bem elaborada tecnicamente. Mas vale lembrar que, para ocasi\u00f5es sofisticadas, os penteados cl\u00e1ssicos s\u00e3o fundamentais&#8221;.<\/p>\n<p>&#8220;Cabelos ultra-lisos e chapados deixam espa\u00e7o para os ondulados e cacheados com a m\u00e1xima naturalidade e sa\u00fade, que poupam a sa\u00fade dos fios. Estes penteados para 2010 dever\u00e3o ser acompanhados de colora\u00e7\u00f5es e balayage com o efeito sun touch, conhecido como luzes californianas, que trazem mais luminosidade e s\u00e3o a cara do ver\u00e3o. De loiros a castanhos m\u00e9dios, acobreados e dourados, estes tons sobrepostos dar\u00e3o o charme da pr\u00f3xima esta\u00e7\u00e3o&#8221;, finaliza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atuando em beleza h\u00e1 mais de duas d\u00e9cadas, o paulistano Marcos Vianna pesquisa e analisa os movimentos que ditam a moda nos cabelos e como as novidades s\u00e3o assimiladas pela mulher brasileira. &#8220;Cabelos longos como as brasileiras gostam s\u00e3o uma marca registrada e fazem o charme; dificilmente em outros pa\u00edses vemos tamanha &#8220;responsabilidade&#8221; da beleza [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-13991","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"has-post-thumbnail","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13991"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13991\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}