{"id":139660,"date":"2018-04-17T12:10:56","date_gmt":"2018-04-17T15:10:56","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=139660"},"modified":"2018-04-17T00:12:59","modified_gmt":"2018-04-17T03:12:59","slug":"novela-luz-do-sol-resumo-18-04-william-enfrenta-agenor","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2018\/novela-luz-do-sol-resumo-18-04-william-enfrenta-agenor\/139660","title":{"rendered":"Novela \u201cLuz do Sol\u201d resumo 18\/04: William enfrenta Agenor"},"content":{"rendered":"<p> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-131397\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Novela \u201cLuz do Sol\u201d resumo 18\/03<\/em><\/strong>: no capitulo 068 (*) da novela \u201cLuz do Sol\u201d, quarta-feira, 18 de abril, Agenor pergunta o que William quer com a mulher dele, na sua casa. William o enfrenta, explicando que foi socorrer a mulher de Agenor e seu filho que estava morrendo, uma vez que n\u00e3o havia um outro homem a quem sua mulher pudesse pedir ajuda. Ver\u00f4nica e Tom batem boca, Belquiss se mete e os acabam se virando contra ela. Agenor amea\u00e7a William e manda recado para Freddy largar do seu p\u00e9. Juarez consegue tirar Lorena da cabeceira de Leonardo, dizendo que o m\u00e9dico deu ordens expressas para que ele fique em repouso absoluto. Belquiss fica revoltada com a maneira que Tom a tratou e acaba revelando que o namoro dos dois era uma arma\u00e7\u00e3o. Ver\u00f4nica diz que s\u00f3 sendo mesmo uma arma\u00e7\u00e3o para o Tom pegar Belquiss, que fica indignada e acaba puxando Ver\u00f4nica pelos cabelos e a joga dentro da banheira de hidromassagem de roupa e tudo. Seguindo a orienta\u00e7\u00e3o de Lorena, Isabela diz a Freddy que n\u00e3o tem certeza de ter visto Leonardo sair de casa armado. Lucio guarda a arma de Leonardo, que poder\u00e1 ser usada para matar algu\u00e9m, mantendo as digitais do dono nela. Ver\u00f4nica pede ajuda a Tom para sair da banheira, mas ele se nega achando que ela ir\u00e1 pux\u00e1-lo para dentro tamb\u00e9m. Ela promete que n\u00e3o far\u00e1 isso, ele acredita, mas ela quebra a promessa e o joga tamb\u00e9m dentro da banheira. Tom agarra Ver\u00f4nica, d\u00e1-lhe um beij\u00e3o e ela empurra a cabe\u00e7a dele na \u00e1gua. Eliana manda recado para Agenor por Mascote, ordenando que ele se afaste dela e de seus filhos, e que n\u00e3o apare\u00e7a mais em casa. Tom jura a Ver\u00f4nica que j\u00e1 se esqueceu do que aconteceu com eles, pois tudo n\u00e3o passou de sexo descart\u00e1vel.<\/p>\n<p>Ofendida, Ver\u00f4nica agarra Tom, d\u00e1-lhe um beij\u00e3o e o leva para cama, prometendo que ele n\u00e3o vai se esquecer daquilo. Freddy n\u00e3o gosta da id\u00e9ia de receber o resultado do exame de DNA de Drica atrav\u00e9s de Marcelo. Zo\u00e9 fica sabendo por Yvonne que Leonardo levou uma surra e vai at\u00e9 a casa dele para saber not\u00edcias. Joaquim abre m\u00e3o ir para a cama com Duda, explicando que ainda n\u00e3o est\u00e1 pronto para isto. Duda fica passada. Eliana pede que William n\u00e3o conte a Drica que Vicente levou um tiro e tamb\u00e9m que ele n\u00e3o se afaste da casa dela, como Agenor mandou. Agenor fica furioso ao saber por Mascote que foi William que internou Vicente numa cl\u00ednica particular e tamb\u00e9m doou sangue para ele. E fica mais transtornado ainda ao saber que Eliana o quer bem longe de casa. Duda diz para Joaquim que tem uma fila de caras atr\u00e1s dela, e que n\u00e3o vai esperar ele resolver o seu \u201cmomento complexo\u201d. Joaquim responde que ela espera se quiser e Duda sai furiosa pedindo que ele a esque\u00e7a. Freddy retira a queixa contra Agenor. Nicanor fica preocupado, pois Tom n\u00e3o dormiu em casa.<\/p>\n<p>Ver\u00f4nica acorda alfinetando Tom, mas acaba se agarrando nele de novo, aos beijos. Mascote avisa a Agenor que a queixa contra ele fora retirada, mas que est\u00e1 devendo muito dinheiro ao advogado. Tanto que Agenor ter\u00e1 que fazer mais um servicinho, ou corre o risco de atirarem em Eliana. Yvonne mostra a Juarez o que achou na casa de Wandinha: uma caixa repleta de fotos de Drica quando era crian\u00e7a. Eug\u00eania chega e pergunta do que se trata. Drica vai at\u00e9 Cleo avisar que far\u00e1 o teste de DNA \u2013 Hel\u00f4 surpreende as duas se abra\u00e7ando, e faz um esc\u00e2ndalo de ci\u00fames da m\u00e3e. Eliana sai do banho e encontra Agenor no quarto, envergonhado, pedindo desculpas. A Pol\u00edcia Federal interdita o estaleiro. <\/p>\n<p>(*) edi\u00e7\u00e3o da Rede Record, Novela \u201cLuz do Sol\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela \u201cLuz do Sol\u201d resumo 18\/03: no capitulo 068 (*) da novela \u201cLuz do Sol\u201d, quarta-feira, 18 de abril, Agenor pergunta o que William quer com a mulher dele, na sua casa. William o enfrenta, explicando que foi socorrer a mulher de Agenor e seu filho que estava morrendo, uma vez que n\u00e3o havia um [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":131397,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[379,371,343],"tags":[441],"class_list":["post-139660","post","type-post","status-publish","format-standard","has-post-thumbnail","category-novelas","category-rede-record","category-televisao","tag-resumo-do-dia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/139660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=139660"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/139660\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/131397"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=139660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=139660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=139660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}