{"id":13879,"date":"2009-10-10T17:43:26","date_gmt":"2009-10-10T21:43:26","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13879"},"modified":"2009-10-10T17:43:26","modified_gmt":"2009-10-10T21:43:26","slug":"lancamento-do-trofeu-raca-negra-2009-sera-terca-feira","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/lancamento-do-trofeu-raca-negra-2009-sera-terca-feira\/13879","title":{"rendered":"Lan\u00e7amento do trof\u00e9u Ra\u00e7a Negra 2009 ser\u00e1 ter\u00e7a-feira"},"content":{"rendered":"<p>A cerim\u00f4nia de lan\u00e7amento do Trof\u00e9u Ra\u00e7a Negra 2009, promovido pela Afrobras, acontece na pr\u00f3xima ter\u00e7a-feira, dia 13\/10, na sede da Coca-Cola Brasil, no Rio de Janeiro. Durante o evento, a Afrobras divulgar\u00e1 a lista dos indicados nas diversas categorias do pr\u00eamio e a campanha de divulga\u00e7\u00e3o do trof\u00e9u, que abranger\u00e1 twitter, um Google profile das promo\u00e7\u00f5es, blogs, sites especializados, entre outras m\u00eddias.\u00a0<\/p>\n<p>A Coca-Cola Brasil patrocina a premia\u00e7\u00e3o criada pela Afrobras, o Trof\u00e9u Ra\u00e7a Negra, desde 2005. Para o evento deste ano, est\u00e3o confirmadas as presen\u00e7as do Ministro Edson Santos, da Secretaria Especial de Pol\u00edticas de Promo\u00e7\u00e3o da Igualdade Racial, da ex-governadora do Rio de Janeiro, Benedita da Silva, dos cantores Neguinho da Beija-Flor, Tony Garrido e Sandra de S\u00e1, e das atrizes Elisa Lucinda, Isabel Fillardis e Sheron Menezes, entre outras personalidades.<\/p>\n<p>Servi\u00e7o:<\/p>\n<p>Evento: Almo\u00e7o de Lan\u00e7amento do Trof\u00e9u Ra\u00e7a Negra 2009<br \/>\nDia: 13 de outubro (ter\u00e7a)<br \/>\nHor\u00e1rio: 11h<br \/>\nLocal: Coca-Cola Brasil<br \/>\nEndere\u00e7o: Praia de Botafogo, 374 \/ 12\u00ba andar &#8211; Botafogo -Rio de Janeiro<\/p>\n<p>Promo\u00e7\u00e3o: ONG Afrobras &#8211; Sociedade Afro-Brasileira de Desenvolvimento S\u00f3cio-Cultural e Faculdade Zumbi dos Palmares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A cerim\u00f4nia de lan\u00e7amento do Trof\u00e9u Ra\u00e7a Negra 2009, promovido pela Afrobras, acontece na pr\u00f3xima ter\u00e7a-feira, dia 13\/10, na sede da Coca-Cola Brasil, no Rio de Janeiro. Durante o evento, a Afrobras divulgar\u00e1 a lista dos indicados nas diversas categorias do pr\u00eamio e a campanha de divulga\u00e7\u00e3o do trof\u00e9u, que abranger\u00e1 twitter, um Google profile [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-13879","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13879"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13879\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}