{"id":13856,"date":"2009-10-10T10:28:02","date_gmt":"2009-10-10T14:28:02","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13856"},"modified":"2009-10-10T10:28:02","modified_gmt":"2009-10-10T14:28:02","slug":"previsao-do-tempo-meteorologia-indica-estado-de-atencao-no-feriado","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/previsao-do-tempo-meteorologia-indica-estado-de-atencao-no-feriado\/13856","title":{"rendered":"Previs\u00e3o do tempo &#8211; meteorologia indica estado de aten\u00e7\u00e3o no feriado"},"content":{"rendered":"<p><strong>Previs\u00e3o do tempo<\/strong> &#8211; Neste s\u00e1bado (10\/10) a <strong>meteorologia<\/strong> informa que \u00e1reas de instabilidade provocar\u00e3o pancadas de chuva entre a BA, norte de MG e de GO, TO, sul e centro do PA, AM e RR. O dia ser\u00e1 bastante nublado com chuvas entre o ES e o sul da BA. No litoral de SP e do PR o tempo estar\u00e1 inst\u00e1vel por causa dos ventos que trazem umidade do mar para o continente. Entre o RJ, sul, centro e noroeste de MG e DF o dia ser\u00e1 nublado com chuvas isoladas. No norte de MT, em RO e no AC haver\u00e1 varia\u00e7\u00e3o de nebulosidade com pancadas de chuva. O dia ser\u00e1 ensolarado entre o sul e oeste do RS, no MS e no sul de MT. Nas outras \u00e1reas do pa\u00eds o sol aparecer\u00e1 entre poucas nuvens. As temperaturas m\u00e1ximas estar\u00e3o amenas no sul e oeste da BA, no ES e no leste de MG e estar\u00e3o elevadas entre SE e o AP.<\/p>\n<p><strong>Estado de Aten\u00e7\u00e3o<\/strong> &#8211; Chuvas fortes voltam a atingir o Sul do Brasil no domingo.\u00a0No s\u00e1bado (10\/10) o dia ser\u00e1 ventoso no litoral do RS. No domingo (11\/10), o tempo come\u00e7ar\u00e1 a mudar novamente na Regi\u00e3o Sul do pa\u00eds. Esperam-se pancadas fortes de chuva e acumulados significativos no RS. No decorrer do dia as pancadas de chuva dever\u00e3o atingir o oeste e faixa sul de SC. A partir da tarde as pancadas fortes de chuva tamb\u00e9m atingir\u00e3o o sul e sudoeste do PR. No litoral do RS o dia ser\u00e1 ventoso.\u00a0Na segunda-feira (12\/10), a tend\u00eancia \u00e9 que as chuvas mais significativas ocorram no nordeste do RS, em SC e no PR. H\u00e1 possibilidade de pancada forte e localizada de chuva no centro-sul e sudoeste de SP e centro-sul e oeste de MS.\u00a0<\/p>\n<p>Nestas dias as chuvas dever\u00e3o vir acompanhadas de raios, descargas el\u00e9tricas e, localmente, n\u00e3o se descarta a ocorr\u00eancia de queda de granizo. \u00a0\u00a0<\/p>\n<p>Estado de Aten\u00e7\u00e3o &#8211; Chuvas forte e acumulado em \u00e1reas de MG, ES, MT, GO, TO, PA, AM, PI, BA e MA.\u00a0No s\u00e1bado (10\/10), haver\u00e1 possibilidade de chuva cont\u00ednua e localmente intensa, com acumulado significativo, no ES (principalmente no norte e litoral norte), norte e nordeste de MG, sul, oeste, centro-sul e leste da BA, sul do PI e do MA, TO, norte de GO, extremo nordeste de MT, centro-sul, leste e nordeste do PA, AM (principalmente o centro-norte e leste) e em RR (principalmente o centro-sul e oeste).\u00a0<\/p>\n<p>No domingo (11\/10) persiste a condi\u00e7\u00e3o de chuva significativa entre ES o litoral do ES, norte de MG, sul, leste, centro-sul e oeste da BA, TO, sul do MA, do PI e do PA. Em situa\u00e7\u00f5es de risco consulte a <a href=\"http:\/\/www.defesacivil.gov.br\/sindec\/estados\/index.asp\" target=\"_blank\">Defesa Civil<\/a>.<\/p>\n<p>CPTEC\/INPE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previs\u00e3o do tempo &#8211; Neste s\u00e1bado (10\/10) a meteorologia informa que \u00e1reas de instabilidade provocar\u00e3o pancadas de chuva entre a BA, norte de MG e de GO, TO, sul e centro do PA, AM e RR. O dia ser\u00e1 bastante nublado com chuvas entre o ES e o sul da BA. No litoral de SP [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,327,376],"tags":[],"class_list":["post-13856","post","type-post","status-publish","format-standard","category-brasil","category-clima","category-clima-brasil","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13856"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13856\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}