{"id":13846,"date":"2009-10-10T10:12:44","date_gmt":"2009-10-10T14:12:44","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13846"},"modified":"2009-10-10T10:12:44","modified_gmt":"2009-10-10T14:12:44","slug":"previsao-do-tempo-na-regiao-nordeste-de-10-a-1210","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/previsao-do-tempo-na-regiao-nordeste-de-10-a-1210\/13846","title":{"rendered":"Previs\u00e3o do tempo na Regi\u00e3o Nordeste de 10 a 12\/10"},"content":{"rendered":"<p><strong>Previs\u00e3o do tempo Regi\u00e3o Nordeste<\/strong> 10\/10\/2009: No sul do MA e do PI e em boa parte da BA: nublado com pancadas de chuva localmente forte. No norte da BA e no centro do PI e do MA: nublado com possibilidade de pancadas de chuva. Nas demais \u00e1reas da Regi\u00e3o: sol entre poucas nuvens. As temperaturas estar\u00e3o est\u00e1veis. Temperaturas m\u00e1xima: 38C no norte do PI. Temperaturas m\u00ednima: 17C no centro de PE.\u00a0<\/p>\n<p>11 e 12\/10\/2009: Na BA e no centro-sul do PI e do MA: nublado com panadas de chuva localmente forte. Nas demais \u00e1reas da Regi\u00e3o: sol entre nuvens. As temperaturas estar\u00e3o est\u00e1veis. Nos pr\u00f3ximos dois dias n\u00e3o haver\u00e1 muitas mudan\u00e7as no tempo.<\/p>\n<p>O Centro de Previs\u00e3o de Tempo e Estudos Clim\u00e1ticos \u2013 CPTEC, do Instituto Nacional de Pesquisas Espaciais \u2013 INPE \u00e9 o passaporte do Brasil para o primeiro mundo das previs\u00f5es meteorol\u00f3gicas. Os supercomputadores vetoriais SX-6 e SX-4 fabricados pela NEC Corporation do Jap\u00e3o, possuem capacidade de processar at\u00e9 768 bilh\u00f5es e 16 bilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo respectivamente. Recentemente adquirido da \u201cNEC Corporation do Jap\u00e3o\u201d um cluster com 1100 processadores fabricado pela \u201cSUN Microsystem\u201d com a capacidade de processar at\u00e9 5.7 trilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo. Isso significa possibilidade de utilizar modelos num\u00e9ricos para simula\u00e7\u00e3o de tempo e clima, integrando informa\u00e7\u00f5es atmosf\u00e9ricas e oce\u00e2nicas. O resultado disso s\u00e3o previs\u00f5es de tempo confi\u00e1veis, para todo o pa\u00eds.\u00a0<\/p>\n<p>CPTEC\/INPE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previs\u00e3o do tempo Regi\u00e3o Nordeste 10\/10\/2009: No sul do MA e do PI e em boa parte da BA: nublado com pancadas de chuva localmente forte. No norte da BA e no centro do PI e do MA: nublado com possibilidade de pancadas de chuva. Nas demais \u00e1reas da Regi\u00e3o: sol entre poucas nuvens. As [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,327],"tags":[],"class_list":["post-13846","post","type-post","status-publish","format-standard","category-brasil","category-clima","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13846"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13846\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}