{"id":13828,"date":"2009-10-09T01:14:56","date_gmt":"2009-10-09T05:14:56","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13828"},"modified":"2009-10-11T19:44:08","modified_gmt":"2009-10-11T23:44:08","slug":"zagueiro-em-busca-da-vaga-na-copa-de-2010","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/zagueiro-em-busca-da-vaga-na-copa-de-2010\/13828","title":{"rendered":"Zagueiro em busca da vaga na Copa de 2010"},"content":{"rendered":"<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/luizao.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-13829\" title=\"luizao\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/luizao-249x187.jpg\" alt=\"luizao\" width=\"249\" height=\"187\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luizao-249x187.jpg 249w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luizao-250x187.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luizao.jpg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luizao-150x113.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luizao-265x198.jpg 265w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luizao-149x112.jpg 149w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/a>O <strong>Brasil<\/strong> est\u00e1 <strong>classificado<\/strong> para a <strong>Copa do Mundo de 2010<\/strong> e, como\u00a0l\u00edder das Eliminat\u00f3rias,\u00a0desfruta de uma situa\u00e7\u00e3o privilegiada que poderia sugerir\u00a0jogos sem press\u00e3o\u00a0contra a Bol\u00edvia, no domingo, e\u00a0quarta-feira contra a Venezuela.<\/p>\n<p>Press\u00e3o pode at\u00e9 n\u00e3o haver.\u00a0Mas obrigatoriedade de vencer existe sempre quando entra em campo a\u00a0Sele\u00e7\u00e3o Brasileira. Bem de acordo com esse esp\u00edrito, que \u00e9 do t\u00e9cnico Dunga e todo o grupo, o zagueiro Luis\u00e3o surge como um dos\u00a0que mais o leva a s\u00e9rio.<\/p>\n<p>Para Luis\u00e3o,\u00a0seja treino ou dois toques j\u00e1 \u00e9 jogo, muito mais para valar passa a ser uma partida de Eliminat\u00f3rias de Copa do Mundo &#8211; n\u00e3o importa se o time j\u00e1 est\u00e1 com o passaporte carimbado para a \u00c1frica do Sul.<\/p>\n<p>Necess\u00e1rio se torna\u00a0ainda que cada um dos\u00a0escolhidos para a viagem\u00a0no ano que vem igualmente carimbe o seu. \u00c9 o que Luis\u00e3o tenta fazer a cada treino, a cada oportunidade que tem de entrar em campo, quando p\u00f5e a\u00a0servi\u00e7o da Sele\u00e7\u00e3o Brasileira\u00a0toda a sua determina\u00e7\u00e3o\u00a0 e ra\u00e7a\u00a0com que disputa uma bola.<\/p>\n<p>Mais do que isso:\u00a0 faz quest\u00e3o de entrar em campo de carra amarrrada &#8211; ele que \u00e9 um cara da paz &#8211; porque adotou a m\u00e1xima de que zagueiro bom \u00e9 aquele que n\u00e3o sorri nunca, como conta ao site CBF.\u00a0<\/p>\n<p>CBF<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Brasil est\u00e1 classificado para a Copa do Mundo de 2010 e, como\u00a0l\u00edder das Eliminat\u00f3rias,\u00a0desfruta de uma situa\u00e7\u00e3o privilegiada que poderia sugerir\u00a0jogos sem press\u00e3o\u00a0contra a Bol\u00edvia, no domingo, e\u00a0quarta-feira contra a Venezuela. Press\u00e3o pode at\u00e9 n\u00e3o haver.\u00a0Mas obrigatoriedade de vencer existe sempre quando entra em campo a\u00a0Sele\u00e7\u00e3o Brasileira. Bem de acordo com esse esp\u00edrito, que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-13828","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"has-post-thumbnail","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13828"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13828\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}