{"id":13814,"date":"2009-10-09T01:02:39","date_gmt":"2009-10-09T05:02:39","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13814"},"modified":"2009-10-23T12:45:09","modified_gmt":"2009-10-23T16:45:09","slug":"pilates-traz-beneficios-que-ultrapassam-os-limites-da-idade","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/pilates-traz-beneficios-que-ultrapassam-os-limites-da-idade\/13814","title":{"rendered":"Pilates traz benef\u00edcios que ultrapassam os limites da idade"},"content":{"rendered":"<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/pilate.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-15024\" title=\"pilate\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/pilate.jpg\" alt=\"pilate\" width=\"150\" height=\"113\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/pilate.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/pilate-148x112.jpg 148w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Joseh Hubertus <strong>Pilates<\/strong> foi uma crian\u00e7a doente, sofria de asma, raquitismo e febre reum\u00e1tica, mas chegou aos 80 anos com uma sa\u00fade invej\u00e1vel gra\u00e7as a atividades criadas por ele e batizadas com seu sobrenome Pilates. A Frase &#8220;corpo s\u00e3o, mente s\u00e3&#8221; sempre fascinou Joseh que, lendo muito sobre medicina e civiliza\u00e7\u00f5es antigas inventou um dos mais revolucion\u00e1rios exerc\u00edcios que temos atualmente. O Pilates faz tamb\u00e9m uma abordagem hol\u00edstica com o corpo, causando uma intera\u00e7\u00e3o entre mente e corpo, conectados para alcan\u00e7ar um resultado.\u00a0<\/p>\n<p>Entre a s\u00e9rie de benef\u00edcios que pode trazer est\u00e1 o aumento da For\u00e7a e controle muscular, melhora no equil\u00edbrio e na coordena\u00e7\u00e3o motora, flexibilidade, previne les\u00f5es, alivia estresse e dores musculares, aumenta concentra\u00e7\u00e3o e auto-estima, al\u00e9m da intera\u00e7\u00e3o entre corpo e mente que o difere de todos os outros exerc\u00edcios. Pode ser praticado por alunos de todas as idades, muito indicado tamb\u00e9m para a terceira idade.<\/p>\n<p>Todos estes benef\u00edcios podem ser encontrados na Shiva Nataraj Dan\u00e7as e Pr\u00e1ticas, que oferecem os melhores treinamentos, respeitando sempre as limita\u00e7\u00f5es de cada pessoa, al\u00e9m de professores que poder\u00e3o n\u00e3o apenas demonstrar as t\u00e9cnicas, mas tamb\u00e9m explicar detalhadamente as raz\u00f5es de cada movimento.<\/p>\n<p>Sobre A Shiva Nataraj\u00a0 &#8211; A Shiva Nataraj academia de dan\u00e7as e pr\u00e1ticas j\u00e1 esta no mercado desde 2001 e tem como lema principal o &#8220;poder da arte&#8221;, ou seja, nos benef\u00edcios que a arte pode trazer aos seus praticantes atrav\u00e9s de movimentos expressivos, harm\u00f4nicos e repletos de significados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Joseh Hubertus Pilates foi uma crian\u00e7a doente, sofria de asma, raquitismo e febre reum\u00e1tica, mas chegou aos 80 anos com uma sa\u00fade invej\u00e1vel gra\u00e7as a atividades criadas por ele e batizadas com seu sobrenome Pilates. A Frase &#8220;corpo s\u00e3o, mente s\u00e3&#8221; sempre fascinou Joseh que, lendo muito sobre medicina e civiliza\u00e7\u00f5es antigas inventou um dos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-13814","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"has-post-thumbnail","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13814"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13814\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}