{"id":13787,"date":"2009-10-09T00:42:17","date_gmt":"2009-10-09T04:42:17","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13787"},"modified":"2009-10-09T00:42:40","modified_gmt":"2009-10-09T04:42:40","slug":"enem-2009-%e2%80%93-mec-devolvera-taxa-de-inscricao-para-alunos-que-desistirem-do-exame","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/enem-2009-%e2%80%93-mec-devolvera-taxa-de-inscricao-para-alunos-que-desistirem-do-exame\/13787","title":{"rendered":"Enem 2009 \u2013 MEC  devolver\u00e1 taxa de inscri\u00e7\u00e3o para alunos que desistirem do exame"},"content":{"rendered":"<p><strong>Enem 2009 MEC<\/strong> &#8211; O ministro da Educa\u00e7\u00e3o, Fernando Haddad, reconheceu como leg\u00edtima a <strong>devolu\u00e7\u00e3o <\/strong>dos R$ 35,00 pagos na<strong> inscri\u00e7\u00e3o<\/strong> do Exame Nacional do Ensino M\u00e9dio (Enem 2009), para os alunos que n\u00e3o desejarem mais fazer a prova, em fun\u00e7\u00e3o da troca da data.\u00a0O MEC estuda os procedimentos para a devolu\u00e7\u00e3o da taxa, que s\u00f3 ser\u00e3o anunciados depois das provas Enem 2009, remarcadas para os dias 5 e 6 de dezembro. Haddad informou nesta quinta-feira, 8, que os estudantes que n\u00e3o quiserem ou puderem fazer a prova na nova data devem enviar uma carta para o Inep fazendo a solicita\u00e7\u00e3o do reembolso.<\/p>\n<p>O endere\u00e7o do Instituto Nacional de Estudos e Pesquisas Educacionais An\u00edsio Teixeira (Inep) \u00e9: SRTVS Quadra 701, Bloco M, Edif\u00edcio Sede do Inep, Bras\u00edlia \u2013 DF. CEP: 70340-909.\u00a0 \u00a0<\/p>\n<p>O sistema de acompanhamento de inscri\u00e7\u00f5es do Exame Nacional do Ensino M\u00e9dio (Enem) de 2009, que permite ao participante redefinir a cidade onde deseja realizar a prova, foi liberado na manh\u00e3 desta ter\u00e7a-feira, 7. Por meio do sistema, os adeptos de religi\u00f5es que guardam o s\u00e1bado ou pessoas com defici\u00eancia, que n\u00e3o declararam essa condi\u00e7\u00e3o no ato da inscri\u00e7\u00e3o, podem faz\u00ea-lo agora. As altera\u00e7\u00f5es Enem 2009 ser\u00e3o feitas at\u00e9 a meia-noite da pr\u00f3xima quarta-feira, dia 14.<\/p>\n<p>Todas as mudan\u00e7as Enem 2009 devem ser feitas na <a href=\"http:\/\/sistemasenem2.inep.gov.br\/Enem2009\">p\u00e1gina<\/a> eletr\u00f4nica do sistema. O inscrito deve selecionar o banner para acompanhamento de inscri\u00e7\u00f5es e informar o CPF e a senha para ter acesso aos dados. Ser\u00e1 poss\u00edvel conferir os dados cadastrais, alterar endere\u00e7o, informar eventuais condi\u00e7\u00f5es especiais necess\u00e1rias para a realiza\u00e7\u00e3o da prova e tamb\u00e9m redefinir o munic\u00edpio \u2014 o sistema, aprimorado para reduzir erros involunt\u00e1rios no processo, pede a confirma\u00e7\u00e3o do munic\u00edpio escolhido para validar a altera\u00e7\u00e3o.<\/p>\n<p>As provas Enem 2009 ser\u00e3o aplicadas nos mesmos 1.829 munic\u00edpios, nos dias 5 e 6 de dezembro. No s\u00e1bado, 5, os participantes far\u00e3o a prova I, de ci\u00eancias da natureza e suas tecnologias e ci\u00eancias humanas e suas tecnologias; no domingo, 6, a prova II, de linguagens, c\u00f3digos e suas tecnologias, mais a reda\u00e7\u00e3o, e matem\u00e1tica e suas tecnologias.<\/p>\n<p>Os hor\u00e1rios Enem 2009 tamb\u00e9m ser\u00e3o mantidos. No s\u00e1bado, 5, o exame come\u00e7a \u00e0s 13h e vai at\u00e9 as 17h30. No domingo, 6, dia da reda\u00e7\u00e3o, as provas ter\u00e3o uma hora a mais \u2014 das 13h \u00e0s 18h30. O hor\u00e1rio \u00e9 o oficial, de Bras\u00edlia.<\/p>\n<p>Todos os participantes Enem 2009 receber\u00e3o, no endere\u00e7o apresentado na inscri\u00e7\u00e3o, um novo comprovante, com o local de prova. O Instituto Nacional de Estudos e Pesquisas Educacionais (Inep) enviar\u00e1, aos participantes que informaram o n\u00famero do telefone celular, torpedos com informa\u00e7\u00e3o do novo local. Assessoria de Comunica\u00e7\u00e3o Social<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enem 2009 MEC &#8211; O ministro da Educa\u00e7\u00e3o, Fernando Haddad, reconheceu como leg\u00edtima a devolu\u00e7\u00e3o dos R$ 35,00 pagos na inscri\u00e7\u00e3o do Exame Nacional do Ensino M\u00e9dio (Enem 2009), para os alunos que n\u00e3o desejarem mais fazer a prova, em fun\u00e7\u00e3o da troca da data.\u00a0O MEC estuda os procedimentos para a devolu\u00e7\u00e3o da taxa, que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-13787","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13787"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13787\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}