{"id":13700,"date":"2009-10-07T14:22:23","date_gmt":"2009-10-07T18:22:23","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13700"},"modified":"2009-10-07T14:23:02","modified_gmt":"2009-10-07T18:23:02","slug":"usp-nao-usara-nota-do-enem-2009-no-vestibular-2010","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/usp-nao-usara-nota-do-enem-2009-no-vestibular-2010\/13700","title":{"rendered":"USP n\u00e3o usar\u00e1 nota do Enem 2009 no vestibular 2010"},"content":{"rendered":"<p>A Universidade de S\u00e3o Paulo (USP) n\u00e3o utilizar\u00e1 a nota do Enem 2009 no vestibular 2010. A decis\u00e3o foi tomada ap\u00f3s o an\u00fancio das novas datas de realiza\u00e7\u00e3o do exame do Enem &#8211; 5 e 6 de dezembro. A altera\u00e7\u00e3o inviabiliza a utiliza\u00e7\u00e3o das notas Enem 2009 \u00a0por raz\u00f5es operacionais.\u00a0Com isso, a nota da primeira fase da Fuvest ser\u00e1 exatamente o n\u00famero de pontos que o candidato obtiver no exame que ser\u00e1 realizado em 22 de novembro.\u00a0<\/p>\n<p>Para os candidatos que optaram pelo INCLUSP, o c\u00e1lculo do b\u00f4nus correspondente \u00e0 nota do Enem 2009 ser\u00e1, excepcionalmente, feito com base no desempenho do candidato no exame da 1\u00aa fase da Fuvest.\u00a0<\/p>\n<p>O calend\u00e1rio e as demais regras do Edital 2010 continuam v\u00e1lidos.<\/p>\n<p>A Universidade Estadual de Campinas (Unicamp) tamb\u00e9m j\u00e1 havia informado que n\u00e3o utilizaria o Enem 2009 neste ano pelos mesmos motivos.<\/p>\n<p>Da USP<\/p>\n<p>Enem 2009 &#8211;\u00a0As provas ser\u00e3o aplicadas nos mesmos 1.829 munic\u00edpios, nos dias 5 e 6 de dezembro. No s\u00e1bado, 5, os participantes far\u00e3o a prova I, de ci\u00eancias da natureza e suas tecnologias e ci\u00eancias humanas e suas tecnologias; no domingo, 6, a prova II, de linguagens, c\u00f3digos e suas tecnologias, mais a reda\u00e7\u00e3o, e matem\u00e1tica e suas tecnologias.<\/p>\n<p>Os hor\u00e1rios tamb\u00e9m ser\u00e3o mantidos. No s\u00e1bado, 5, o exame come\u00e7a \u00e0s 13h e vai at\u00e9 as 17h30. No domingo, 6, dia da reda\u00e7\u00e3o, as provas ter\u00e3o uma hora a mais \u2014 das 13h \u00e0s 18h30. O hor\u00e1rio \u00e9 o oficial, de Bras\u00edlia.<\/p>\n<p>Todos os participantes receber\u00e3o, no endere\u00e7o apresentado na inscri\u00e7\u00e3o, um novo comprovante, com o local de prova. O Instituto Nacional de Estudos e Pesquisas Educacionais (Inep) enviar\u00e1, aos participantes que informaram o n\u00famero do telefone celular, torpedos com informa\u00e7\u00e3o do novo local.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Universidade de S\u00e3o Paulo (USP) n\u00e3o utilizar\u00e1 a nota do Enem 2009 no vestibular 2010. A decis\u00e3o foi tomada ap\u00f3s o an\u00fancio das novas datas de realiza\u00e7\u00e3o do exame do Enem &#8211; 5 e 6 de dezembro. A altera\u00e7\u00e3o inviabiliza a utiliza\u00e7\u00e3o das notas Enem 2009 \u00a0por raz\u00f5es operacionais.\u00a0Com isso, a nota da primeira [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-13700","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13700"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13700\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}