{"id":13695,"date":"2009-10-07T12:32:47","date_gmt":"2009-10-07T16:32:47","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13695"},"modified":"2009-10-07T12:32:47","modified_gmt":"2009-10-07T16:32:47","slug":"exportar-para-crescer-acontece-em-novembro","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/exportar-para-crescer-acontece-em-novembro\/13695","title":{"rendered":"Exportar para Crescer acontece em novembro"},"content":{"rendered":"<p>O projeto, que faz parte do programa Exporta S\u00e3o Paulo da Federa\u00e7\u00e3o das Associa\u00e7\u00f5es Comerciais do Estado de S\u00e3o Paulo (Facesp), tem por objetivo mobilizar e sensibilizar produtores de pequeno porte para neg\u00f3cios de exporta\u00e7\u00e3o, atrav\u00e9s de semin\u00e1rios, encontro de neg\u00f3cios e despachos executivos, com entidades e empresas que atuam no com\u00e9rcio internacional.<\/p>\n<p>O semin\u00e1rio divulga as a\u00e7\u00f5es da Secretaria de Ci\u00eancia, Tecnologia e Desenvolvimento Econ\u00f4mico do Estado de S\u00e3o Paulo (SCTDE-SP) para o fomento do com\u00e9rcio exterior do Estado, apresenta os trabalhos do Projeto Exporta S\u00e3o Paulo e discute op\u00e7\u00f5es de racionaliza\u00e7\u00e3o da log\u00edstica e das opera\u00e7\u00f5es financeiras de exportadores de pequeno porte, que, geralmente, lidam com lotes de valores inferiores a US$ 10 mil, por embarque.<\/p>\n<p>&#8220;Guarulhos conta, hoje, com mais de 3.200 empresas com potencial para exportar. Espero que possamos incentivar potenciais exportadores j\u00e1 que, apesar da crise, existem oportunidades claras para incremento dos neg\u00f3cios&#8221;, disse Jos\u00e9 Roberto Vitorelli, diretor de com\u00e9rcio exterior da ACE.<\/p>\n<p>A 2\u00aa edi\u00e7\u00e3o do Exportar para Crescer conta com o apoio da Nuno Ferreira Cargas Internacionais, J. Valle Safety Cargo e Exata Comex Log\u00edstica Aduaneira. Informa\u00e7\u00f5es sobre o Exportar para Crescer atrav\u00e9s da Central de Relacionamento da ACE: (11) 2137-9333.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O projeto, que faz parte do programa Exporta S\u00e3o Paulo da Federa\u00e7\u00e3o das Associa\u00e7\u00f5es Comerciais do Estado de S\u00e3o Paulo (Facesp), tem por objetivo mobilizar e sensibilizar produtores de pequeno porte para neg\u00f3cios de exporta\u00e7\u00e3o, atrav\u00e9s de semin\u00e1rios, encontro de neg\u00f3cios e despachos executivos, com entidades e empresas que atuam no com\u00e9rcio internacional. O semin\u00e1rio [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-13695","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13695"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13695\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}