{"id":13618,"date":"2009-10-06T17:03:56","date_gmt":"2009-10-06T21:03:56","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13618"},"modified":"2009-10-06T17:05:42","modified_gmt":"2009-10-06T21:05:42","slug":"enem-2009-%e2%80%93-nova-prova-sera-em-dezembro","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/enem-2009-%e2%80%93-nova-prova-sera-em-dezembro\/13618","title":{"rendered":"Enem 2009 \u2013 nova data da prova ser\u00e1 em dezembro"},"content":{"rendered":"<p><strong>Enem 2009<\/strong> \u00a0&#8211; as <strong>novas provas<\/strong> do Exame Nacional do Ensino M\u00e9dio (Enem 2009) j\u00e1 t\u00eam <strong>nova data<\/strong>: 5 e 6 de dezembro (s\u00e1bado e domingo). O an\u00fancio foi feito pelo ministro da Educa\u00e7\u00e3o, Fernando Haddad, nesta ter\u00e7a-feira, 6, ap\u00f3s reuni\u00e3o com o ministro da Justi\u00e7a, Tarso Genro. No encontro entre os ministros, ficou definida a participa\u00e7\u00e3o da For\u00e7a Nacional e da Pol\u00edcia Federal em todas as etapas da log\u00edstica da prova.<\/p>\n<p>\u201cA Pol\u00edcia Federal vai acompanhar todo o processo Enem 2009, desde a sa\u00edda da prova do cofre do Inep at\u00e9 a distribui\u00e7\u00e3o das provas, que dever\u00e1 ser feita pelos correios\u201d, disse Haddad. Caso seja acertada a participa\u00e7\u00e3o dos correios na log\u00edstica do Enem, a distribui\u00e7\u00e3o do material impresso ser\u00e1 feito por meio de uma opera\u00e7\u00e3o especial, \u201ccercada de garantias para que as provas cheguem aos destinos corretamente\u201d, nas palavras do ministro.<\/p>\n<p>A partir de agora, a equipe do setor de intelig\u00eancia da Pol\u00edcia Federal vai elaborar os detalhes do monitoramento de cada etapa da log\u00edstica do Enem 2009. \u201cO exame \u00e9 um \u00edcone nacional e o desafio do Estado \u00e9 zelar para que o instrumento seja aplicado de maneira adequada\u201d, enfatizou Haddad.<\/p>\n<p>O ministro ressaltou que a Secretaria de Educa\u00e7\u00e3o Superior (Sesu) do MEC tem mantido contato com as universidades que tinham vestibular marcado para o primeiro fim de semana de dezembro, para que entrem em consenso sobre nova data. Entre as universidades federais que aplicariam vestibular nesses dias e j\u00e1 confirmaram adequa\u00e7\u00e3o \u00e0 nova data Enem 2009\u00a0est\u00e3o a de Juiz de Fora, de Santa Catarina e a Universidade de Bras\u00edlia.<\/p>\n<p>Ainda nesta ter\u00e7a-feira haver\u00e1 uma reuni\u00e3o entre representantes do Minist\u00e9rio da Educa\u00e7\u00e3o, do Centro de Sele\u00e7\u00e3o e Promo\u00e7\u00e3o de Eventos da Universidade de Bras\u00edlia (Cespe) e da Funda\u00e7\u00e3o Cesgranrio, que v\u00e3o aplicar a prova Enem 2009, para definir detalhes de corre\u00e7\u00e3o e divulga\u00e7\u00e3o do resultado do exame.\u00a0<\/p>\n<p>Assessoria de Comunica\u00e7\u00e3o Social<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enem 2009 \u00a0&#8211; as novas provas do Exame Nacional do Ensino M\u00e9dio (Enem 2009) j\u00e1 t\u00eam nova data: 5 e 6 de dezembro (s\u00e1bado e domingo). O an\u00fancio foi feito pelo ministro da Educa\u00e7\u00e3o, Fernando Haddad, nesta ter\u00e7a-feira, 6, ap\u00f3s reuni\u00e3o com o ministro da Justi\u00e7a, Tarso Genro. No encontro entre os ministros, ficou definida [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":["post-13618","post","type-post","status-publish","format-standard","category-brasil","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13618"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13618\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}