{"id":13584,"date":"2009-10-06T14:40:57","date_gmt":"2009-10-06T18:40:57","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13584"},"modified":"2009-10-06T14:40:57","modified_gmt":"2009-10-06T18:40:57","slug":"brasileiros-desconhecem-cuidados-adequados-com-os-rins","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/brasileiros-desconhecem-cuidados-adequados-com-os-rins\/13584","title":{"rendered":"Brasileiros desconhecem cuidados adequados com os rins"},"content":{"rendered":"<p>Quando o assunto \u00e9 cuidado com os rins, aten\u00e7\u00e3o e informa\u00e7\u00e3o s\u00e3o mais que necess\u00e1rios. Para avaliar a percep\u00e7\u00e3o da popula\u00e7\u00e3o acerca deste tema, a Funda\u00e7\u00e3o Pr\u00f3-Renal Brasil, com o apoio da Roche, encomendou ao Instituto Datafolha uma pesquisa para avaliar o conhecimento dos brasileiros sobre problemas renais. De acordo com o levantamento, 7 em cada 10 pessoas dizem tomar alguma atitude no dia a dia para preservar a sa\u00fade renal. O problema \u00e9 que a alternativa mais mencionada para atingir esse objetivo foi a ingest\u00e3o de \u00e1gua (63%).\u00a0<\/p>\n<p>Os n\u00fameros s\u00e3o extremamente importantes, pois refletem o desconhecimento da popula\u00e7\u00e3o acerca de problemas que podem acometer os rins. De acordo com especialistas, a ingest\u00e3o de \u00e1gua n\u00e3o \u00e9 a principal atitude que deve ser tomada para garantir a sa\u00fade renal. &#8220;N\u00e3o h\u00e1 evid\u00eancia cient\u00edfica de que tomar muita \u00e1gua preserva a sa\u00fade dos rins. O pr\u00f3prio organismo tem um sistema altamente sens\u00edvel para controlar essa ingest\u00e3o, que \u00e9 a sede. Por isso, al\u00e9m da \u00e1gua, os cuidados adequados com os rins devem incluir alimenta\u00e7\u00e3o saud\u00e1vel e controle de doen\u00e7as como diabetes, hipertens\u00e3o, inflama\u00e7\u00f5es e infec\u00e7\u00f5es&#8221;, explica Miguel Riella, nefrologista e presidente da Funda\u00e7\u00e3o Pr\u00f3-Renal Brasil.<\/p>\n<p>Outro dado preocupante \u00e9 que apenas 30% das pessoas souberam apontar doen\u00e7as que podem gerar les\u00f5es graves nos rins, como o diabetes e a press\u00e3o alta. Para Riella, esse n\u00famero tamb\u00e9m revela a falta de conhecimento dos brasileiros. &#8220;Essas enfermidades, comuns e cada vez mais crescentes no Brasil, figuram como as principais causas da doen\u00e7a renal cr\u00f4nica (DRC), que resulta na incapacidade irrevers\u00edvel das fun\u00e7\u00f5es dos rins. O agravante \u00e9 que, se os pacientes n\u00e3o tem essa informa\u00e7\u00e3o e n\u00e3o fazem o controle dessas doen\u00e7as, seus rins poder\u00e3o ser gravemente lesionados pela DRC. E a doen\u00e7a n\u00e3o apresenta sintomas at\u00e9 que as fun\u00e7\u00f5es renais estejam comprometidas em at\u00e9 75%&#8221;, afirma o nefrologista. &#8220;Quando chega neste est\u00e1gio, a DRC pode gerar consequ\u00eancias grav\u00edssimas, podendo levar o paciente \u00e0 necessidade de hemodi\u00e1lise e at\u00e9 transplantes&#8221;, conclui.<\/p>\n<p>Anemia<\/p>\n<p>Quando questionadas se problemas renais podem se agravar e causar anemia, 42% das pessoas responderam que n\u00e3o e 10% n\u00e3o souberam dizer. Isso mostra que parte significativa da popula\u00e7\u00e3o desconhece a anemia renal e, consequentemente, n\u00e3o est\u00e1 atenta aos seus complicadores. &#8220;H\u00e1 muitas pessoas que s\u00f3 conhecem a anemia provocada pela falta de ferro e n\u00e3o sabem que existe e nem o que \u00e9 a anemia associada \u00e0 doen\u00e7a renal cr\u00f4nica&#8221;, explica Riella.<\/p>\n<p>Estat\u00edsticas mundiais mostram que mais de 500 milh\u00f5es de pessoas tem algum grau de DRC. Elas sofrem com uma deteriora\u00e7\u00e3o da fun\u00e7\u00e3o renal que pode durar v\u00e1rios anos at\u00e9 que seja necess\u00e1ria uma terapia para a substitui\u00e7\u00e3o do rim. Quando \u00e9 constatada a fal\u00eancia desses \u00f3rg\u00e3os, os pacientes n\u00e3o conseguem secretar eritropoietina, horm\u00f4nio produzido pelos rins que estimulam a fabrica\u00e7\u00e3o de gl\u00f3bulos vermelhos na medula \u00f3ssea. Sendo assim, eles desenvolvem anemia, diagnosticada atrav\u00e9s do exame que mede os n\u00edveis de hemoglobina (prote\u00edna que carrega o oxig\u00eanio dentro dos gl\u00f3bulos vermelhos).<\/p>\n<p>A anemia renal pode acometer os pacientes com DRC j\u00e1 nos est\u00e1gios iniciais e piora \u00e0 medida que ocorre perda progressiva das fun\u00e7\u00f5es renais. Cerca de 95% dos pacientes com doen\u00e7a cr\u00f4nica renal que necessitam de di\u00e1lise (procedimento que faz a filtra\u00e7\u00e3o do sangue) apresentam um quadro de anemia renal cr\u00f4nica. A enfermidade prejudica o transporte e utiliza\u00e7\u00e3o de oxig\u00eanio em tecidos e \u00f3rg\u00e3os do organismo, apresentando efeitos como fraqueza, cansa\u00e7o, palpita\u00e7\u00f5es, dificuldade de concentra\u00e7\u00e3o e tonturas, que afetam tanto a qualidade de vida quanto a sa\u00fade e o bem-estar.<\/p>\n<p>Em grande parte dos casos, quando tratada tardiamente, a anemia renal contribui para o aparecimento de complica\u00e7\u00f5es cardiovasculares, como o aumento do tamanho do cora\u00e7\u00e3o e a acelera\u00e7\u00e3o no ritmo de bombeamento do sangue em busca de compensa\u00e7\u00e3o para a falta de oxigena\u00e7\u00e3o no corpo.<\/p>\n<p>Tratamento adequado<\/p>\n<p>Aprovado em 87 pa\u00edses, inclusive no Brasil, o Mircera (betaepoetina-metoxipolietilenoglico), medicamento produzido pelo laborat\u00f3rio Roche para tratamento da anemia associada \u00e0 DRC, consegue estabilizar o n\u00edvel de gl\u00f3bulos vermelhos, tratar a anemia renal e devolver a qualidade de vida aos pacientes com apenas uma inje\u00e7\u00e3o mensal. Pelo menos 70% dos doentes tratados com Mircera (betaepoetina-metoxipolietilenoglico) ficam com os n\u00edveis de hemoglobina est\u00e1veis. Estudos e an\u00e1lises recentes tem confirmado a efic\u00e1cia da droga, que \u00e9 o primeiro agente estimulante da eritropoiese a oferecer terapia mensal.<\/p>\n<p>Especialidade m\u00e9dica<\/p>\n<p>Questionados sobre a hip\u00f3tese de terem problemas nos rins, 54% dos entrevistados n\u00e3o saberia qual especialista procurar para tratar o problema e apenas 5% buscariam um nefrologista, especialidade adequada para o tratamento de problemas renais. Do restante, 25% procurariam um cl\u00ednico geral e 11%, um urologista.<\/p>\n<p>&#8220;\u00c9 importante que a especialidade de nefrologia fique atenta \u00e0 quantidade de casos que podem aumentar nos pr\u00f3ximos anos, por conta do crescimento do n\u00famero de diab\u00e9ticos e hipertensos. Hoje temos pouco mais de 3 mil nefrologistas no territ\u00f3rio nacional &#8211; este n\u00famero tende a aumentar para dar conta da demanda&#8221;, explica Riella.<\/p>\n<p>Outros resultados<\/p>\n<p>O Instituto Datafolha ouviu 2.556 pessoas, com 16 anos ou mais, de 180 munic\u00edpios brasileiros, entre os dias 26 e 28 de maio deste ano. A m\u00e9dia de idade da amostragem foi de 38 anos e a distribui\u00e7\u00e3o por sexo foi equivalente entre homens e mulheres. Outros dados constatados foram:<\/p>\n<p>&#8211; Tomar muita \u00e1gua \u00e9 h\u00e1bito mais comum em mulheres &#8211; 67%.<\/p>\n<p>&#8211; 25% procurariam um cl\u00ednico geral para o tratamento de problemas renais; 11%, um urologista e 5% procurariam um nefrologista. 54% n\u00e3o saberiam qual especialidade procurar.<\/p>\n<p>&#8211; 45% souberam apontar causas para a anemia. As mais mencionadas foram falta de ferro (23%) e alimenta\u00e7\u00e3o inadequada (14%). &#8211; Apenas 28% das pessoas souberam apontar as conseq\u00fc\u00eancias da anemia. Fraqueza (19%) e cansa\u00e7o (8%) foram as mais mencionadas.<\/p>\n<p>&#8211; 62% das pessoas apontaram algum sintoma de problema renal. Dificuldade de urinar (24%) e dores na regi\u00e3o da barriga (24%) s\u00e3o os sintomas de doen\u00e7as renais mais conhecidos pelos brasileiros.<\/p>\n<p>&#8211; A baixa escolaridade do brasileiro tem reflexos na falta de conhecimento sobre problemas renais.<\/p>\n<p>Informa\u00e7\u00f5es \u00dateis:<\/p>\n<p>&#8211; No Brasil, aproximadamente 90 mil pessoas est\u00e3o em di\u00e1lise e 95% delas sofre de anemia renal. Dados do Censo 2008 da Sociedade Brasileira de Nefrologia (SBN) mostram que o n\u00famero de pacientes submetidos \u00e0 di\u00e1lise cresce ao menos 8% ao ano.<\/p>\n<p>&#8211; O tratamento dos pacientes em di\u00e1lise consome cerca de 10% do or\u00e7amento da sa\u00fade no Brasil.<\/p>\n<p>&#8211; 70% dos casos de pacientes com DRC desenvolveram a doen\u00e7a por conta da diabetes e hipertens\u00e3o. De acordo com a Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS), mais de 150 milh\u00f5es de pessoas no mundo sofrem de diabetes e estima-se que esse n\u00famero dobre nas pr\u00f3ximas d\u00e9cadas. A hipertens\u00e3o tamb\u00e9m \u00e9 considerada uma epidemia pela OMS e atinge 1 bilh\u00e3o de pessoas em todo o mundo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando o assunto \u00e9 cuidado com os rins, aten\u00e7\u00e3o e informa\u00e7\u00e3o s\u00e3o mais que necess\u00e1rios. Para avaliar a percep\u00e7\u00e3o da popula\u00e7\u00e3o acerca deste tema, a Funda\u00e7\u00e3o Pr\u00f3-Renal Brasil, com o apoio da Roche, encomendou ao Instituto Datafolha uma pesquisa para avaliar o conhecimento dos brasileiros sobre problemas renais. De acordo com o levantamento, 7 em [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,5],"tags":[],"class_list":["post-13584","post","type-post","status-publish","format-standard","category-brasil","category-saude-e-vida","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13584"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13584\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}