{"id":13575,"date":"2009-10-06T14:28:44","date_gmt":"2009-10-06T18:28:44","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13575"},"modified":"2009-10-06T14:28:44","modified_gmt":"2009-10-06T18:28:44","slug":"campanha-diga-nao-aos-rodeios","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/campanha-diga-nao-aos-rodeios\/13575","title":{"rendered":"Campanha &#8220;diga n\u00e3o aos rodeios!&#8221;"},"content":{"rendered":"<p>Nesta quarta-feira, dia 7 de outubro, \u00e0s 10h, na C\u00e2mara Municipal de Guarulhos, acontecer\u00e1 uma audi\u00eancia p\u00fablica para debater a volta dos rodeios ao munic\u00edpio de Guarulhos. O vereador Z\u00e9 Luiz (PT), autor da Lei Municipal 6.033\/04, que proibiu a utiliza\u00e7\u00e3o de animais em circos, rodeios, cavalhadas e vaquejadas, convoca todos os defensores dos animais para uma mobiliza\u00e7\u00e3o que impe\u00e7a a volta \u00e0 cidade desses verdadeiros espet\u00e1culos de tortura.\u00a0<\/p>\n<p>Isso acontece porque h\u00e1 na C\u00e2mara Municipal um Projeto de Lei cujo intuito \u00e9 alterar a reda\u00e7\u00e3o da Lei 6.033\/04 do Z\u00e9 Luiz e permitir a volta dos rodeios a Guarulhos. Para n\u00e3o deixar isso acontecer, al\u00e9m da presen\u00e7a de todos na audi\u00eancia p\u00fablica, o vereador Z\u00e9 Luiz tamb\u00e9m lan\u00e7ou uma campanha para coletar o maior n\u00famero poss\u00edvel de assinaturas de pessoas contra a volta dos rodeios. O abaixo-assinado virtual pode ser acessado em www.abaixoassinado.org\/abaixoassinados\/5081.<\/p>\n<p>&#8220;Temos de promover uma grande mobiliza\u00e7\u00e3o para impedir a volta desse show de horrores a Guarulhos. A Lei Municipal que conseguimos aprovar em 2004 e proibiu os maus tratos aos animais em espet\u00e1culos terr\u00edveis com a pretensa inten\u00e7\u00e3o de divers\u00e3o j\u00e1 foi uma enorme vit\u00f3ria. N\u00e3o podemos deixar esse retrocesso acontecer. Espero que todos ajudem a divulgar o abaixo-assinado e compare\u00e7am para apoiar a causa na audi\u00eancia p\u00fablica&#8221;, afirma Z\u00e9 Luiz.<\/p>\n<p>No blog do Z\u00e9 Luiz, \u00e9 poss\u00edvel obter mais informa\u00e7\u00f5es: www.zeluizpt.blogspot.com.br.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta quarta-feira, dia 7 de outubro, \u00e0s 10h, na C\u00e2mara Municipal de Guarulhos, acontecer\u00e1 uma audi\u00eancia p\u00fablica para debater a volta dos rodeios ao munic\u00edpio de Guarulhos. O vereador Z\u00e9 Luiz (PT), autor da Lei Municipal 6.033\/04, que proibiu a utiliza\u00e7\u00e3o de animais em circos, rodeios, cavalhadas e vaquejadas, convoca todos os defensores dos animais [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-13575","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13575"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13575\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}