{"id":13566,"date":"2009-10-06T14:20:03","date_gmt":"2009-10-06T18:20:03","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13566"},"modified":"2009-10-06T14:20:03","modified_gmt":"2009-10-06T18:20:03","slug":"infertilidade-quilos-a-mais-ou-a-menos-dificultam-gravidez","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/infertilidade-quilos-a-mais-ou-a-menos-dificultam-gravidez\/13566","title":{"rendered":"Infertilidade: quilos a mais ou a menos dificultam gravidez"},"content":{"rendered":"<p>Como tudo na vida exige um equil\u00edbrio, no caso da gesta\u00e7\u00e3o n\u00e3o \u00e9 diferente. Poucas mulheres sabem, mas peso demais ou de menos pode ser um obst\u00e1culo na vida de quem deseja engravidar. A infertilidade, de acordo com a Organiza\u00e7\u00e3o Mundial da Sa\u00fade, \u00e9 um dist\u00farbio mais comum do que parece e afeta entre 15% e 20% dos casais no mundo.\u00a0<\/p>\n<p>De acordo com o ginecologista e obstetra Newton Busso, fundador do Projeto Beta de Reprodu\u00e7\u00e3o Assistida com Responsabilidade Social e Professor de Ci\u00eancias M\u00e9dicas da Santa Casa de S\u00e3o Paulo, o excesso de peso implica na produ\u00e7\u00e3o elevada de determinados horm\u00f4nios que podem interromper a ovula\u00e7\u00e3o. Estat\u00edsticas apontam que entre 8% e 10% das mulheres que desejam engravidar encontram-se acima do peso.<\/p>\n<p>&#8220;Com quilos extras, \u00e9 comum a mulher ter ciclos irregulares, ovular com menor freq\u00fc\u00eancia e assim ter as chances de gesta\u00e7\u00e3o reduzidas. Isso acontece porque o aumento da gordura corporal eleva a produ\u00e7\u00e3o de estr\u00f3geno que provoca um desequil\u00edbrio que manda uma mensagem \u00e0 hip\u00f3fise de que n\u00e3o \u00e9 mais necess\u00e1rio liberar mais horm\u00f4nios aos ov\u00e1rios&#8221;, esclarece o m\u00e9dico.<\/p>\n<p>O ideal nesses casos \u00e9 a mudan\u00e7a de h\u00e1bito: a ado\u00e7\u00e3o de uma dieta equilibrada associada \u00e0 pr\u00e1tica regular de exerc\u00edcios f\u00edsicos.<\/p>\n<p>E mais: a obesidade tamb\u00e9m altera os n\u00edveis de insulina liberados pelo p\u00e2ncreas, desencadeando uma superprodu\u00e7\u00e3o de horm\u00f4nios masculinos e gerando uma interrup\u00e7\u00e3o na libera\u00e7\u00e3o dos \u00f3vulos.<\/p>\n<p>Por outro lado, um \u00edndice de gordura corporal abaixo de 17% significa uma produ\u00e7\u00e3o menor de determinados horm\u00f4nios, como o estr\u00f3geno, por exemplo, e uma possibilidade de interrup\u00e7\u00e3o na ovula\u00e7\u00e3o. Muitas vezes, lembra o especialista, essa magreza excessiva est\u00e1 associada \u00e0 pr\u00e1tica desmedida e exagerada do esporte ou envolve casos mais graves de anorexia ou bulimia.<\/p>\n<p>Quem se encaixa em um dos casos acima e est\u00e1 tentando engravidar, deve procurar a ajuda de um especialista para investigar o que est\u00e1 acontecendo com o organismo. De acordo com a Organiza\u00e7\u00e3o Mundial de Sa\u00fade, inf\u00e9rteis s\u00e3o aqueles casais que estejam tentando engravidar h\u00e1 mais de um ano, mant\u00eam rela\u00e7\u00f5es sexuais com freq\u00fcencia e n\u00e3o usam m\u00e9todos contraceptivos.<\/p>\n<p>Sobre o Projeto Beta<br \/>\nCriado em 2005 por um grupo de m\u00e9dicos e professores universit\u00e1rios, o Beta oferece qualidade assistencial e tratamento humano na \u00e1rea da infertilidade, adequando o pre\u00e7o \u00e0s condi\u00e7\u00f5es financeiras do casal. Formado por uma equipe multidisciplinar composta por ginecologistas, urologistas, enfermeiros, bi\u00f3logos e biom\u00e9dicos, o projeto, localizado no bairro da Bela Vista, em S\u00e3o Paulo, oferece todo tipo de tratamento na \u00e1rea da reprodu\u00e7\u00e3o assistida. Uma vez ao m\u00eas, sempre aos s\u00e1bados, o Projeto Beta oferece palestras gratuitas para tirar d\u00favidas sobre o assunto.<br \/>\nHaver\u00e1 palestras nos dias 10\/10 e 21\/11. Elas acontecem na Rua Cincinato Braga, 37, no bairro da Bela Vista, em S\u00e3o Paulo. \u00c9 necess\u00e1rio confirmar presen\u00e7a antes pelo tel. 0\/xx\/11\/3826-7017, de segunda a sexta, das 8h00 \u00e0s 18h00. Mais informa\u00e7\u00f5es no site <a href=\"http:\/\/www.projetobeta.com.br\/ \" target=\"_blank\">http:\/\/www.projetobeta.com.br\/\u00a0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como tudo na vida exige um equil\u00edbrio, no caso da gesta\u00e7\u00e3o n\u00e3o \u00e9 diferente. Poucas mulheres sabem, mas peso demais ou de menos pode ser um obst\u00e1culo na vida de quem deseja engravidar. A infertilidade, de acordo com a Organiza\u00e7\u00e3o Mundial da Sa\u00fade, \u00e9 um dist\u00farbio mais comum do que parece e afeta entre 15% [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":["post-13566","post","type-post","status-publish","format-standard","category-brasil","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13566"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13566\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}