{"id":13451,"date":"2009-10-05T16:39:50","date_gmt":"2009-10-05T20:39:50","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13451"},"modified":"2009-10-05T16:39:50","modified_gmt":"2009-10-05T20:39:50","slug":"kodak-lanca-primeira-filmadora-de-bolso-em-alta-definicao-do-brasil","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/kodak-lanca-primeira-filmadora-de-bolso-em-alta-definicao-do-brasil\/13451","title":{"rendered":"KODAK lan\u00e7a primeira filmadora de bolso em alta defini\u00e7\u00e3o do Brasil"},"content":{"rendered":"<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/filmadora.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-13452\" title=\"filmadora\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/filmadora-249x187.jpg\" alt=\"filmadora\" width=\"249\" height=\"187\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/filmadora-249x187.jpg 249w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/filmadora-250x187.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/filmadora.jpg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/filmadora-150x113.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/filmadora-265x198.jpg 265w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/filmadora-149x112.jpg 149w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/a>A Kodak Brasileira apresenta a novidade que trar\u00e1 ao consumidor uma experi\u00eancia \u00fanica em captura de imagens: Kodak Zx1, a primeira filmadora de bolso em alta defini\u00e7\u00e3o do Pa\u00eds. Com visor LCD de 2 polegadas, zoom digital 2x e capacidade para filmar em alta ou baixa luminosidade, o lan\u00e7amento \u00e9 perfeito para acompanhar qualquer aventura, em qualquer lugar. Com a Zx1 o consumidor \u00e9 o diretor de seus filmes e pode escolher a qualidade de v\u00eddeo que preferir: HD60 (60 FPS), HD30 (30 FPS) ou VGA, e assim reviver os melhores momentos em slow motion na palma da m\u00e3o.\u00a0<\/p>\n<p>Compacta, a Zx1 pesa menos de 100 gramas e tem mem\u00f3ria interna de 128MB, al\u00e9m de capturar \u00e1udio de forma n\u00edtida com um microfone de baixa distor\u00e7\u00e3o. O software integrado para edi\u00e7\u00e3o \u00e9 um excelente recurso para criar clipes personalizados com fotos e m\u00fasicas favoritas. Para completar, \u00e9 poss\u00edvel fazer o upload de seus v\u00eddeos no YouTubeT com a facilidade do software ArcSoft\u00ae Media Impression.<\/p>\n<p>Zx1: a filmadora aventureira<\/p>\n<p>A Kodak Zx1 \u00e9 a companhia essencial para encarar desafios e aventuras! Resistente a respingos de \u00e1gua, neve, areia e terra, a filmadora est\u00e1 de acordo com o Padr\u00e3o IP43, o qual determina que a filmadora foi desenvolvida para suportar todas as condi\u00e7\u00f5es clim\u00e1ticas que possam danificar equipamentos eletr\u00f4nicos. O revestimento emborrachado e o acabamento em a\u00e7o, al\u00e9m de proteger o sistema, d\u00e3o um toque inovador com design arrojado \u00e0 Kodak Zx1.<\/p>\n<p>&#8220;Para a Kodak \u00e9 essencial que o consumidor experimente novas formas de eternizar suas mem\u00f3rias. Com isso em mente, estudamos o mercado e encontramos a oportunidade para trazer ao Brasil a Zx1, que eleva o patamar de captura de imagens e coloca nosso portf\u00f3lio em um n\u00edvel diferenciado&#8221; diz Emerson Stein, diretor geral da Divis\u00e3o de Consumo da Kodak Brasileira. &#8220;Essa novidade trar\u00e1 ao mercado modernidade, praticidade e custo-benef\u00edcio, tudo isso em um \u00fanico equipamento.&#8221;<\/p>\n<p>Vers\u00e1til, a Zx1 pode ser comprada nas cores preta, pink e vermelha, e chega o Brasil com o pre\u00e7o sugerido de R$ 699. A nova filmadora da Kodak ser\u00e1 vendida pela Internet, varejo especializado e lojas de eletroeletr\u00f4nicos de todo Pa\u00eds. Para mais informa\u00e7\u00f5es sobre esse ou outros produtos acesse www.kodak.com.br.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Kodak Brasileira apresenta a novidade que trar\u00e1 ao consumidor uma experi\u00eancia \u00fanica em captura de imagens: Kodak Zx1, a primeira filmadora de bolso em alta defini\u00e7\u00e3o do Pa\u00eds. Com visor LCD de 2 polegadas, zoom digital 2x e capacidade para filmar em alta ou baixa luminosidade, o lan\u00e7amento \u00e9 perfeito para acompanhar qualquer aventura, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":["post-13451","post","type-post","status-publish","format-standard","category-brasil","entry","has-post-thumbnail","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13451"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13451\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}