{"id":13442,"date":"2009-10-05T15:08:27","date_gmt":"2009-10-05T19:08:27","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13442"},"modified":"2009-10-05T15:08:27","modified_gmt":"2009-10-05T19:08:27","slug":"palestra-com-amauri-crozariolli-e-aclamada-pelo-publico-em-ji-parana","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/palestra-com-amauri-crozariolli-e-aclamada-pelo-publico-em-ji-parana\/13442","title":{"rendered":"Palestra com Amauri Crozariolli \u00e9 aclamada pelo p\u00fablico em Ji-Paran\u00e1"},"content":{"rendered":"<p>Com o tema &#8220;Perspectivas e Mudan\u00e7as do Comportamento Profissional&#8221;, a palestra realizada na noite desta sexta-feira (02), no audit\u00f3rio do Ceulji\/Ulbra, pela Associa\u00e7\u00e3o Comercial e Industrial de Ji-Paran\u00e1 (ACIJIP) em parceria com a Federa\u00e7\u00e3o das Associa\u00e7\u00f5es Comerciais e Industriais do Estado de Rondonia (Facer) foi um verdadeiro show, como destacou os participantes. Convidado para ministrar o tema, o consultor empresarial Amauri Crozariolli, com muita interatividade conseguiu sorrisos e a participa\u00e7\u00e3o integral de toda a plat\u00e9ia.\u00a0<\/p>\n<p>A palestra que durou aproximadamente duas horas foi envolvida por par\u00f3dias e teve a aceita\u00e7\u00e3o geral de todos que assistiram. \u201cO trabalho da ACIJIP tem sido focado nessa promo\u00e7\u00e3o de capacita\u00e7\u00e3o e treinamentos em todo segmento. Ficamos felizes com a satisfa\u00e7\u00e3o do p\u00fablico\u201d, ressaltou o presidente Marcito Pinto.<\/p>\n<p>Para o empres\u00e1rio Agnaldo de S\u00e1, palestras desse n\u00edvel deveriam ser mais freq\u00fcentes em Ji-Paran\u00e1 n\u00e3o s\u00f3 para estimular o envolvimento dos colaboradores como tamb\u00e9m dos donos das empresas. \u201cUm dos maiores desafios da nossa realidade \u00e9 a forma\u00e7\u00e3o de equipes na regi\u00e3o. Trabalhamos diariamente na forma\u00e7\u00e3o de profissionais e precisamos de eventos como esse promovido pela ACIJIP para capacitar essas pessoas. Precisamos acordar para a realidade do mercado e o palestrante soube mostrar isso muito bem. Foi uma palestra maravilhosa. Parab\u00e9ns pela brilhante escolha do tema\u201d, destacou.<\/p>\n<p>Aplaudido de p\u00e9 ao final da palestra, o consultor empresarial enfatizou a necessidade do mercado em se encarar mudan\u00e7as, quebrar paradigmas e aproveitar as oportunidades. \u201c\u00c9 preciso assumir essas responsabilidades para se gerar resultados e satisfa\u00e7\u00e3o profissional. Gostei muito de conhecer o Estado de Rond\u00f4nia que se mostrou muito receptivo. Vejo infinitas oportunidades de trabalho para todos nessa regi\u00e3o\u201d, finalizou. \u00a0<\/p>\n<p>Assessoria ACIJIP<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o tema &#8220;Perspectivas e Mudan\u00e7as do Comportamento Profissional&#8221;, a palestra realizada na noite desta sexta-feira (02), no audit\u00f3rio do Ceulji\/Ulbra, pela Associa\u00e7\u00e3o Comercial e Industrial de Ji-Paran\u00e1 (ACIJIP) em parceria com a Federa\u00e7\u00e3o das Associa\u00e7\u00f5es Comerciais e Industriais do Estado de Rondonia (Facer) foi um verdadeiro show, como destacou os participantes. Convidado para ministrar [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":["post-13442","post","type-post","status-publish","format-standard","category-brasil","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13442"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13442\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}