{"id":13418,"date":"2009-10-05T09:30:37","date_gmt":"2009-10-05T13:30:37","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13418"},"modified":"2009-10-05T09:30:37","modified_gmt":"2009-10-05T13:30:37","slug":"fator-previdenciario-e-reajuste-da-aposentadoria-%e2%80%93-lider-do-pdt-deve-assinar-requerimento-da-cobap","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/fator-previdenciario-e-reajuste-da-aposentadoria-%e2%80%93-lider-do-pdt-deve-assinar-requerimento-da-cobap\/13418","title":{"rendered":"Fator Previdenci\u00e1rio e Reajuste da Aposentadoria \u2013 L\u00edder do PDT deve assinar requerimento da COBAP"},"content":{"rendered":"<p>Indignado com o crescimento generalizado do n\u00famero de idosos em situa\u00e7\u00e3o miser\u00e1vel, o deputado federal Jo\u00e3o Dado, do PDT-SP, declarou que o maior crime que j\u00e1 cometeram neste Pa\u00eds (praticados pelos governantes do passado e do presente) foi a dilapida\u00e7\u00e3o do patrim\u00f4nio da Previd\u00eancia Social e o achatamento dos benef\u00edcios de milh\u00f5es de aposentados e pensionistas. Dado efetua um mandato parlamentar em perfeita simetria com as reivindica\u00e7\u00f5es da <strong>COBAP<\/strong>, defendendo publicamente a urgente aprova\u00e7\u00e3o do <strong>reajuste<\/strong> no mesmo percentual do sal\u00e1rio m\u00ednimo extensivo \u00e0 todos (<strong>PL 01\/07<\/strong>), a extin\u00e7\u00e3o definitiva do <strong>fator previdenci\u00e1rio<\/strong> (<strong>PL 3299\/08<\/strong>) e a <strong>recomposi\u00e7\u00e3o das aposentadorias<\/strong> defasadas (<strong>PL 4434\/08<\/strong>).<\/p>\n<p>Segundo Jo\u00e3o Dado, seu partido \u00e9 totalmente favor\u00e1vel \u00e0s causas dos aposentados e sua bancada certamente votar\u00e1 maci\u00e7amente no PL 01, assim que for colocado em pauta. As palavras do parlamentar paulista foram endossadas pelo presidente nacional do PDT, Vieira da Cunha. Em conversa telef\u00f4nica com o presidente da COBAP, Warley Martins, o deputado ga\u00facho Vieirinha informou que o <strong>l\u00edder do PDT<\/strong> na C\u00e2mara, Dagoberto, vai assinar o <strong>requerimento<\/strong> que pede urg\u00eancia na vota\u00e7\u00e3o do projeto.<\/p>\n<p>Forjado no movimento sindical, Dado \u00e9 autor de projetos e emendas que beneficiam diretamente milh\u00f5es de trabalhadores da ativa e aposentados.<\/p>\n<p>Aposentados 05\/10\/2009 | Por Richard Casal<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Indignado com o crescimento generalizado do n\u00famero de idosos em situa\u00e7\u00e3o miser\u00e1vel, o deputado federal Jo\u00e3o Dado, do PDT-SP, declarou que o maior crime que j\u00e1 cometeram neste Pa\u00eds (praticados pelos governantes do passado e do presente) foi a dilapida\u00e7\u00e3o do patrim\u00f4nio da Previd\u00eancia Social e o achatamento dos benef\u00edcios de milh\u00f5es de aposentados e [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,7],"tags":[],"class_list":["post-13418","post","type-post","status-publish","format-standard","category-brasil","category-economia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13418"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13418\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}