{"id":13372,"date":"2009-10-03T12:47:05","date_gmt":"2009-10-03T16:47:05","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13372"},"modified":"2009-10-03T12:47:05","modified_gmt":"2009-10-03T16:47:05","slug":"dois-fortissimos-tufoes-atuam-no-oceano-pacifico-noroeste","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/dois-fortissimos-tufoes-atuam-no-oceano-pacifico-noroeste\/13372","title":{"rendered":"Dois fort\u00edssimos tuf\u00f5es atuam no oceano pac\u00edfico noroeste"},"content":{"rendered":"<p>Somar Meteorologia &#8211; O tuf\u00e3o Parma, que surgiu no Oceano Pac\u00edfico Noroeste no dia 27 de setembro na regi\u00e3o da Micron\u00e9sia, perdeu um pouco de for\u00e7a nesta madrugada. Por\u00e9m, Parma ainda \u00e9 classificado como tuf\u00e3o de n\u00edvel 4 escala Saffir-Simpson, com ventos de 216km\/h\/h. As \u00faltimas simula\u00e7\u00f5es indicam que Parma dever\u00e1 perder for\u00e7a nas pr\u00f3ximas horas, conforme avan\u00e7a para o norte das Filipinas, mas ainda com ventos intensos. H\u00e1 alerta vermelho para chuvas e ventos fortes para as Filipinas ainda hoje e amarelo para Taiwan para ter\u00e7a-feira.<\/p>\n<p>A tempestade tropical Melor, que surgiu no dia 29 de setembro no Oceano Pac\u00edfico Noroeste em alto-mar, a leste da Micron\u00e9sia, ganhou for\u00e7a e agora \u00e9 classifcado como tuf\u00e3o de n\u00edvel 4 na escala Saffir-Simpson de classifica\u00e7\u00e3o de furac\u00f5es. Melor mant\u00e9m ventos de 220km\/h nesta sexta-feira. Tudo indica que este tuf\u00e3o dever\u00e1 ganhar ainda mais for\u00e7a e atingir a categoria 5 dentro no domingo. H\u00e1 alerta vermelho para chuvas e ventos fortes na ilhas Marianas e Guam nos pr\u00f3ximos dias.<\/p>\n<p>Do outro lado do Oceano Pac\u00edfico, surgiu a tempestade tropical Olaf, com ventos de 72km\/h. Olaf est\u00e1 posicionado a cerca de 450 quil\u00f4metros a oeste do M\u00e9xico e as \u00faltimas simula\u00e7\u00f5es indicam que dever\u00e1 seguir em dire\u00e7\u00e3o \u00e0 Baixa Calif\u00f3rnia nos pr\u00f3ximos dias. N\u00e3o h\u00e1 expectativa por enquanto desta tempestade se tornar furac\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Somar Meteorologia &#8211; O tuf\u00e3o Parma, que surgiu no Oceano Pac\u00edfico Noroeste no dia 27 de setembro na regi\u00e3o da Micron\u00e9sia, perdeu um pouco de for\u00e7a nesta madrugada. Por\u00e9m, Parma ainda \u00e9 classificado como tuf\u00e3o de n\u00edvel 4 escala Saffir-Simpson, com ventos de 216km\/h\/h. As \u00faltimas simula\u00e7\u00f5es indicam que Parma dever\u00e1 perder for\u00e7a nas pr\u00f3ximas [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,327],"tags":[],"class_list":["post-13372","post","type-post","status-publish","format-standard","category-brasil","category-clima","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13372"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13372\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}