{"id":13363,"date":"2009-10-03T12:14:41","date_gmt":"2009-10-03T16:14:41","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13363"},"modified":"2009-10-03T12:14:41","modified_gmt":"2009-10-03T16:14:41","slug":"precos-agricolas-sp-fecham-setembro-com-alta-de-022","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/precos-agricolas-sp-fecham-setembro-com-alta-de-022\/13363","title":{"rendered":"Pre\u00e7os agr\u00edcolas SP fecham setembro com alta de 0,22%"},"content":{"rendered":"<p>O \u00cdndice Quadrissemanal de Pre\u00e7os Recebidos pela Agropecu\u00e1ria Paulista &#8211; IqPR fechou o m\u00eas de setembro com varia\u00e7\u00e3o positiva de 0,22%, segundo o Instituto de Economia Agr\u00edcola &#8211; IEA\/Apta da Secretaria de Agricultura e Abastecimento. No acumulado de um ano (setembro\/08 a setembro\/09), o \u00edndice geral mostra varia\u00e7\u00e3o positiva de 4,22% e o \u00edndice de produtos vegetais avan\u00e7a 12,49%. Por sua vez, o \u00edndice de produtos animais sofreu varia\u00e7\u00e3o negativa de 14,67%. Sem computar a cana-de-a\u00e7\u00facar no c\u00e1lculo, o \u00edndice geral apresentou queda significativa de 4,63%, embora o \u00edndice de produtos vegetais tenha evolu\u00eddo positivamente em 5,04%, informam Eder Pinatti, Jos\u00e9 Alberto \u00c2ngelo, Jos\u00e9 Sidnei Gon\u00e7alves e Luis Henrique Perez, pesquisadores do Instituto.\u00a0<\/p>\n<p>Os aumentos mensais mais expressivos foram verificados nos pre\u00e7os da laranja para mesa (20,43%), da carne su\u00edna (6,89%) e da laranja para ind\u00fastria (2,07%). A retomada das aulas, concomitante com o fim do per\u00edodo mais duro de inverno, eleva o consumo da laranja (para mesa), al\u00e9m da menor concorr\u00eancia da laranja para ind\u00fastria no consumo in-natura, em virtude da redu\u00e7\u00e3o na sua oferta para este fim, dizem os autores da an\u00e1lise.<\/p>\n<p>&#8220;Mas da \u00f3tica da renda do citricultor o processo pode ser considerado de recupera\u00e7\u00e3o de pre\u00e7os, uma vez que os mesmos se mant\u00eam 30,66% inferiores aos verificados em igual per\u00edodo do ano de 2008.&#8221; O mesmo pode se dizer da laranja para ind\u00fastria, cujos pre\u00e7os aumentaram pouco, mas ainda se mant\u00eam muito baixos em rela\u00e7\u00e3o ao ano anterior (-34,03%). &#8220;Noutras palavras, os pre\u00e7os da laranja em geral se mostram em torno de um ter\u00e7o inferiores aos verificados em 2008.&#8221;<\/p>\n<p>A alta do pre\u00e7o da carne su\u00edna decorre do aumento da demanda, principalmente por parte da ind\u00fastria, que est\u00e1 incrementando a produ\u00e7\u00e3o de derivados de carne su\u00edna, com vistas ao consumo do final do ano e tamb\u00e9m da redu\u00e7\u00e3o da produ\u00e7\u00e3o, dizem os pesquisadores do IEA. &#8220;Nos \u00faltimos meses, os pre\u00e7os da carne su\u00edna ficaram abaixo do esperado, por conta da influ\u00eancia da gripe A (ainda erroneamente chamada de gripe su\u00edna). Por\u00e9m as cota\u00e7\u00f5es mostram recupera\u00e7\u00e3o parcial, visto que, em m\u00e9dia, est\u00e3o na mesma faixa dos pre\u00e7os praticados no mesmo per\u00edodo de 2007, mas ainda menores (-31,15%) em rela\u00e7\u00e3o ao mesmo per\u00edodo de 2008.&#8221;<\/p>\n<p>J\u00e1 as quedas mais significativas foram observadas nos pre\u00e7os do tomate para mesa (18,80%), do feij\u00e3o (12,29%), da carne de frango (9,48%), dos ovos (7,76%) e do arroz (3,77%). No caso do feij\u00e3o, &#8220;incrementa-se a entrada da produ\u00e7\u00e3o de inverno, ocasionando a redu\u00e7\u00e3o das cota\u00e7\u00f5es, numa realidade de pre\u00e7os j\u00e1 baixos em rela\u00e7\u00e3o ao ano passado. Ademais as safras, em especial da agropecu\u00e1ria de subsist\u00eancia do Nordeste, foram muito boas, ampliando ainda mais a oferta nesse momento, empurrando os pre\u00e7os para baixo&#8221;, observam os t\u00e9cnicos.<\/p>\n<p>Os pesquisadores ressaltam que, &#8220;boas colheitas de feij\u00e3o n\u00e3o necessariamente representam maior renda bruta, pois quando o produtor tem boa produ\u00e7\u00e3o n\u00e3o tem bom pre\u00e7o e quando tem bom pre\u00e7o \u00e9 porque n\u00e3o tem o produto. As cota\u00e7\u00f5es atuais desestimulam o plantio das \u00e1guas, quando nas regi\u00f5es produtoras paulistas essa lavoura alimentar concorre com a soja&#8221;.<\/p>\n<p>Para a carne de frango, os pesquisadores observam que o aumento da oferta derrubou as cota\u00e7\u00f5es do produto numa realidade tamb\u00e9m de menor press\u00e3o de demanda. &#8220;Com o efeito em cadeia, atinge-se o mercado de milho (enquanto insumo da avicultura), cuja produ\u00e7\u00e3o se mostra acima da demanda, restrita pela queda das exporta\u00e7\u00f5es e do pre\u00e7o da carne bovina &#8211; produto substituto- tamb\u00e9m por raz\u00f5es semelhantes. A isso se somam os efeitos da aprecia\u00e7\u00e3o cambial que pressiona para baixo os pre\u00e7os internos.&#8221;<\/p>\n<p>No acumulado de setembro\/2008 a setembro\/2009, as maiores varia\u00e7\u00f5es positivas ocorreram nos pre\u00e7os da batata (162,50%), do tomate para mesa (43,97%), da banana nanica (34,33%) &#8211; produtos onde a sazonalidade e o clima foram os principais fatores pela eleva\u00e7\u00e3o dos pre\u00e7os &#8211; e da cana-de-a\u00e7\u00facar (17,70%), cujas condi\u00e7\u00f5es favor\u00e1veis do mercado internacional do a\u00e7\u00facar, em rela\u00e7\u00e3o ao ano passado, sustentam a eleva\u00e7\u00e3o dos \u00faltimos doze meses. J\u00e1 as quedas mais fortes ocorreram nas cota\u00e7\u00f5es do feij\u00e3o (64,81%), do amendoim (40,88%), da laranja para ind\u00fastria (34,03%), da carne su\u00edna (31,15%), da laranja para mesa (30,66%), da carne de frango (26,79%) e dos ovos (20,41%).<\/p>\n<p>Entre os produtos brasileiros com relev\u00e2ncia internacional, o patamar de pre\u00e7os da soja \u00e9 similar ao do ano anterior, &#8220;ou seja, a continuidade do crescimento da economia chinesa &#8211; importante mercado para a soja brasileira &#8211; vem sustentando o patamar dos pre\u00e7os internacionais dessa oleaginosa. Vale destacar ainda as varia\u00e7\u00f5es negativas para a carne bovina, milho e arroz&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O \u00cdndice Quadrissemanal de Pre\u00e7os Recebidos pela Agropecu\u00e1ria Paulista &#8211; IqPR fechou o m\u00eas de setembro com varia\u00e7\u00e3o positiva de 0,22%, segundo o Instituto de Economia Agr\u00edcola &#8211; IEA\/Apta da Secretaria de Agricultura e Abastecimento. No acumulado de um ano (setembro\/08 a setembro\/09), o \u00edndice geral mostra varia\u00e7\u00e3o positiva de 4,22% e o \u00edndice de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,7],"tags":[],"class_list":{"0":"post-13363","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"category-economia","8":"entry","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13363"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13363\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}