{"id":13226,"date":"2009-10-01T14:29:46","date_gmt":"2009-10-01T18:29:46","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=13226"},"modified":"2009-10-01T14:29:46","modified_gmt":"2009-10-01T18:29:46","slug":"nova-data-do-enem-2009","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/nova-data-do-enem-2009\/13226","title":{"rendered":"Nova data do Enem 2009"},"content":{"rendered":"<p><strong>MEC<\/strong> <strong>Nova data<\/strong> do <strong>Enem 2009<\/strong>\u00a0&#8211; Aos mais de 4,1 milh\u00f5es de estudantes inscritos no Enem, este ano, o ministro da educa\u00e7\u00e3o assegurou que as provas ser\u00e3o realizadas em novembro, no prazo de 45 dias, aproximadamente. A previs\u00e3o de Haddad \u00e9 que a nova data seja anunciada na pr\u00f3xima semana.\u00a0As provas do Exame Nacional do Ensino M\u00e9dio (Enem), marcadas para s\u00e1bado, 3, e domingo, 4, foram adiadas pelo Minist\u00e9rio da Educa\u00e7\u00e3o. O motivo, segundo o ministro Fernando Haddad, foi o vazamento das provas ocorrido na noite de quarta-feira, 30 de setembro, em S\u00e3o Paulo.<\/p>\n<p>Em entrevista coletiva no in\u00edcio da tarde desta quinta-feira, dia 1\u00ba, em Bras\u00edlia, Haddad comunicou o adiamento do Enem e as duas primeiras provid\u00eancias que tomou \u2014 pediu ao superintendente da Pol\u00edcia Federal, Luiz Fernando Corr\u00eaa, a abertura de inqu\u00e9rito para apurar o vazamento das provas e convocou o cons\u00f3rcio Consultec, vencedor da licita\u00e7\u00e3o para todas as etapas de realiza\u00e7\u00e3o do Enem, para uma reuni\u00e3o de emerg\u00eancia, ainda na tarde desta quinta-feira, no Minist\u00e9rio da Educa\u00e7\u00e3o MEC.<\/p>\n<p>Ao mesmo tempo em que a Pol\u00edcia Federal vai investigar o caso, o Minist\u00e9rio da Educa\u00e7\u00e3o elaborar\u00e1 as novas provas, que devem ser aplicadas em novembro. O ministro salientou que os inscritos no Enem ser\u00e3o devidamente comunicados sobre a nova data e todas as mudan\u00e7as a serem feitas.<\/p>\n<p>Enem 2009 MEC &#8211; Ionice Lorenzoni<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MEC Nova data do Enem 2009\u00a0&#8211; Aos mais de 4,1 milh\u00f5es de estudantes inscritos no Enem, este ano, o ministro da educa\u00e7\u00e3o assegurou que as provas ser\u00e3o realizadas em novembro, no prazo de 45 dias, aproximadamente. A previs\u00e3o de Haddad \u00e9 que a nova data seja anunciada na pr\u00f3xima semana.\u00a0As provas do Exame Nacional do [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-13226","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=13226"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/13226\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=13226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=13226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=13226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}