{"id":129913,"date":"2017-12-27T19:28:16","date_gmt":"2017-12-27T21:28:16","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=129913"},"modified":"2017-12-27T19:49:27","modified_gmt":"2017-12-27T21:49:27","slug":"resumo-novela-sortilegio-28-12-fernando-previne-alessandro-sobre-maura-e-bruno","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2017\/resumo-novela-sortilegio-28-12-fernando-previne-alessandro-sobre-maura-e-bruno\/129913","title":{"rendered":"Resumo novela \u201cSortil\u00e9gio\u201d 28\/12: Fernando previne Alessandro sobre Maura e Bruno"},"content":{"rendered":"<p><strong><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-60833\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/sortilegio_novela_resumo_sbt-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/sortilegio_novela_resumo_sbt-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/sortilegio_novela_resumo_sbt-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>Resumo novela \u201cSortil\u00e9gio\u201d 28\/12<\/em><\/strong>: no cap\u00edtulo 053(*) da novela \u201cSortil\u00e9gio\u201d, resumo de quinta-feira, 28 de dezembro, Maura tenta convencer Alessandro que Helena a procurou para tentar se aproximar de Maria Jos\u00e9 e Paula. Muito doente, o sogro de Helena diz a Jorge que fez um novo testamento e ter\u00e1 que mant\u00ea-lo vivo at\u00e9 que sua neta volte. Raquel est\u00e1 em crise de abstin\u00eancia por causa do \u00e1lcool e diz a Vit\u00f3ria que quer se livrar da filha. Fernando diz a Vit\u00f3ria que n\u00e3o sabe mais o que fazer com K\u00e1tia e afirma que ela continua seu relacionamento com Bruno. Alessandro diz a Maria Jos\u00e9 que sua m\u00e3e quer v\u00ea-la, mas a aconselha a n\u00e3o se encontrar com ela depois de tantos anos de abandono. <\/p>\n<p>Maria Jos\u00e9 diz que s\u00f3 gostaria que lhe dissesse por que as abandonou. Desconfiado que Helena e Maura fizeram um acordo, Ulisses amea\u00e7a contar tudo a Porf\u00edrio se for tirado da jogada. Jorge d\u00e1 uma inje\u00e7\u00e3o para que Porf\u00edrio passe a maior parte do tempo dormindo para que n\u00e3o atrapalhe seus planos. Maura se aproxima de Maria Jos\u00e9 com a desculpa que quer ajud\u00e1-la a organizar seu casamento e diz que Alessandro lhe pediu que encontrasse uma casa para eles. <\/p>\n<p>Vit\u00f3ria ouve a conversa e entristece ao saber que Alessandro e Maria Jos\u00e9 pretendem deixar a mans\u00e3o. Maria Jos\u00e9 explica que eles n\u00e3o suportam a presen\u00e7a de Bruno. Fernando previne Alessandro e diz que nem Maura nem Bruno v\u00e3o sossegar enquanto n\u00e3o o separar de Maria Jos\u00e9. Jorge e Helena contam a Maura os planos que tem para Maria Jos\u00e9 e dizem que assim ela ter\u00e1 o caminho livre para conquistar Alessandro.<\/p>\n<p>(*) edi\u00e7\u00e3o do SBT, Novela \u201cSortil\u00e9gio\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>A trama conta uma hist\u00f3ria de enganos e trai\u00e7\u00f5es, onde o \u00f3dio que Bruno sente por seu meio-irm\u00e3o Alessandro, o leva a planejar sua morte s\u00f3 para se tornar herdeiro de sua fortuna. Vit\u00f3ria teve um caso com o amigo de seu marido Samuel, Antonio Lombardo, resultando no nascimento de g\u00eameos: Bruno e Raquel. Antonio tamb\u00e9m teve um filho, Alessandro, com sua esposa Adriana. Depois de seus respectivos c\u00f4njuges morreram, Vit\u00f3ria e Ant\u00f4nio come\u00e7aram um relacionamento e se casaram. No entanto, eles n\u00e3o disseram a seus filhos que eram meio-irm\u00e3os, j\u00e1 que revelaria suas infidelidades. Em vez disso, criaram seus filhos que reconhecerem-se mutuamente como meio-irm\u00e3os. Os anos passam, e Bruno vem a ser um homem irrespons\u00e1vel que n\u00e3o respeita as leis. Alessandro, por outro lado, \u00e9 muito respons\u00e1vel. Antonio prefere Alessandro a Bruno, e decide que Alessandro deve herdar seu dinheiro quando morrer. Antonio e Vit\u00f3ria v\u00e3o \u00e1 uma reuni\u00e3o na escola de Bruno sobre seu comportamento, e lhe \u00e9 dito que ele foi expulso. Enquanto eles est\u00e3o deixando o local, eles come\u00e7am uma discuss\u00e3o e distra\u00eddo, Antonio prende suas muletas em um buraco. Vit\u00f3ria que est\u00e1 brava com ele por causa de seus argumentos, continua andando e n\u00e3o ajuda o marido. Quando Antonio tenta se libertar, um homem em uma motocicleta se choca contra ele, causando a morte de Antonio. Vit\u00f3ria torna-se novamente vi\u00fava. Algum tempo depois, Fernando, amigo de Alessandro, se apaixona por Vit\u00f3ria, mas seu amor n\u00e3o pode acontecer por causa da diferen\u00e7a de idade. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo novela \u201cSortil\u00e9gio\u201d 28\/12: no cap\u00edtulo 053(*) da novela \u201cSortil\u00e9gio\u201d, resumo de quinta-feira, 28 de dezembro, Maura tenta convencer Alessandro que Helena a procurou para tentar se aproximar de Maria Jos\u00e9 e Paula. Muito doente, o sogro de Helena diz a Jorge que fez um novo testamento e ter\u00e1 que mant\u00ea-lo vivo at\u00e9 que sua [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":60833,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[379,372,343],"tags":[441],"class_list":{"0":"post-129913","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-sbt","9":"category-televisao","10":"tag-resumo-do-dia","11":"entry","12":"gs-1","13":"gs-odd","14":"gs-even","15":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/sortilegio_novela_resumo_sbt.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/129913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=129913"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/129913\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/60833"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=129913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=129913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=129913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}