{"id":12925,"date":"2009-09-28T15:30:56","date_gmt":"2009-09-28T19:30:56","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=12925"},"modified":"2009-09-28T15:30:56","modified_gmt":"2009-09-28T19:30:56","slug":"novidades-long-jump-para-o-dia-das-criancas","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/novidades-long-jump-para-o-dia-das-criancas\/12925","title":{"rendered":"Novidades Long Jump para o Dia das Crian\u00e7as"},"content":{"rendered":"<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/skate.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-12926\" title=\"skate\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/skate.jpg\" alt=\"skate\" width=\"150\" height=\"113\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/skate.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/skate-148x112.jpg 148w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Simpsons, bicicletas com painel, aqua sand, skates do Bob Burnquist, Bakugan e pel\u00facia do Pocoyo. Estas s\u00e3o <strong>novidades<\/strong> que a Long Jump vai lan\u00e7ar em todo o Brasil especialmente para o <strong>Dia da Crian\u00e7a<\/strong>. Com mais de 400 itens em sua linha de produtos, a Long Jump tem um pacote especial para a data. Dos consagrados Simpsons, a empresa apresenta a miniatura de todos os personagens que agora, em comemora\u00e7\u00e3o ao 20\u00ba anivers\u00e1rio do desenho, v\u00eam com roupagem especial.\u00a0<\/p>\n<p>A outra aposta para a data s\u00e3o as Bicicletas com painel dos personagens Carros, Ariel e Princesas, fabricadas no Brasil pela Long Jump. Al\u00e9m de toda a caracteriza\u00e7\u00e3o e graciosidade dos personagens, o painel, que \u00e9 interativo, emite som e luzes. O Aqua Sand \u00e9 mais uma atra\u00e7\u00e3o. \u00c9 a areia m\u00e1gica, que colocada na \u00e1gua resulta em formas incr\u00edveis, e o mais intrigrante: quando a crian\u00e7a tira a areia da \u00e1gua, ela est\u00e1 completamente seca.<\/p>\n<p>Bob Burnquist, o consagrado skatista brasileiro, desenvolveu em parceria com a Long Jump, uma linha de skates semiprofissionais e produtos de seguran\u00e7a, semiprofissionais, e com um detalhe bem especial: Bob aprovou e autografou os oito modelos diferentes de skate.<\/p>\n<p>A empresa tamb\u00e9m sugere os Bakugans, Guerreiros da Batalha, consagrado nos Estados Unidos e no Jap\u00e3o como um dos melhores lan\u00e7amentos dos \u00faltimos tempos. Bakugan s\u00e3o as esferas que explodem. O kit vem com cards e os Bakugans, que lan\u00e7ados nos cards magn\u00e9ticos abrem e mostram o personagem. Cada participante deve jogar o Bakugan no Gate Card (um cart\u00e3o magn\u00e9tico que quando o Bakugan est\u00e1 em cima ele se abre). Ganha quem somar mais pontos, juntando os pontos de cada Bakugan aos aceleradores dos Gates Cards<\/p>\n<p>Por fim, a pel\u00facia do carism\u00e1tico Pocoyo, confeccionada em material de alta qualidade e hipoalerg\u00eanico, ou seja, dificilmente vai despertar algum tipo de alergia.<\/p>\n<p>www.longjump.com.br \/ sac@longjump.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Simpsons, bicicletas com painel, aqua sand, skates do Bob Burnquist, Bakugan e pel\u00facia do Pocoyo. Estas s\u00e3o novidades que a Long Jump vai lan\u00e7ar em todo o Brasil especialmente para o Dia da Crian\u00e7a. Com mais de 400 itens em sua linha de produtos, a Long Jump tem um pacote especial para a data. Dos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-12925","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"has-post-thumbnail","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/12925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=12925"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/12925\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=12925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=12925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=12925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}