{"id":129178,"date":"2017-12-19T16:51:34","date_gmt":"2017-12-19T18:51:34","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=129178"},"modified":"2017-12-19T16:51:34","modified_gmt":"2017-12-19T18:51:34","slug":"resumo-novela-carinha-de-anjo-20-12-haydee-e-a-herdeira-da-fortuna-de-nicole","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2017\/resumo-novela-carinha-de-anjo-20-12-haydee-e-a-herdeira-da-fortuna-de-nicole\/129178","title":{"rendered":"Resumo novela \u201cCarinha de Anjo\u201d 20\/12: Haydee \u00e9 a herdeira da fortuna de Nicole"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-99331\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/carinha_de_anjo_sbt_novela_resumo_capitulo-150x112.jpg\" alt=\"carinha_de_anjo_sbt_novela_resumo_capitulo\" width=\"150\" height=\"112\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/carinha_de_anjo_sbt_novela_resumo_capitulo-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/carinha_de_anjo_sbt_novela_resumo_capitulo-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Resumo novela \u201cCarinha de Anjo\u201d 20\/12<\/em><\/strong>: no cap\u00edtulo 283(*) da novela \u201cCarinha de Anjo\u201d, resumo de quarta-feira, 20 de dezembro, Franciely descobre que Leonardo na verdade \u00e9 irm\u00e3o de Estef\u00e2nia e que mentiu para ela. Mais tarde, a Tia Perucas conversa com Franciely e as duas pedem para que Silvestre marque uma consulta para elas irem at\u00e9 a cartomante que ele conhece. As religiosas prestam depoimento na delegacia, para Peixoto, sobre a tentativa de sequestro de Dulce Maria. Haydee recebe a visita do advogado sobre a heran\u00e7a de Nicole e revela para Fl\u00e1vio que ela \u00e9 a herdeira direta da fortuna e que o filho n\u00e3o vai ver nenhum tost\u00e3o do dinheiro, pois ela n\u00e3o quer passar por problemas financeiros como no passado. Haydee diz ainda que ir\u00e1 dar uma reformada no apartamento e o restante do dinheiro ir\u00e1 aplicar. Leonardo inventa uma falsa hist\u00f3ria para Silvana com objetivo de tentar fazer ela se apaixonar. <\/p>\n<p>(*) edi\u00e7\u00e3o do SBT, Novela \u201cCarinha de Anjo\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado. <\/p>\n<p>Carinha de Anjo \u00e9 uma telenovela brasileira produzida e exibida originalmente pelo SBT desde o dia 21 de novembro de 2016, substituindo o hor\u00e1rio anteriormente ocupado por C\u00famplices de um Resgate. A telenovela \u00e9 inspirada na mexicana Carita de \u00e1ngel, que, por sua vez, \u00e9 um remake de Mundo de juguete, ambas produzidas pela Televisa e que haviam sido baseadas na trama argentina escrita por Abel Santa Cruz, Pap\u00e1 coraz\u00f3n. Esta ser\u00e1 a segunda adapta\u00e7\u00e3o brasileira da obra original argentina, visto que a Rede Tupi apresentou em 1976 a sua primeira vers\u00e3o, chamada de Papai Cora\u00e7\u00e3o. A nova vers\u00e3o \u00e9 escrita por Leonor Corr\u00eaa, com supervis\u00e3o de \u00cdris Abravanel e dire\u00e7\u00e3o geral de Ricardo Mantoanelli. A trama conta com Lorena Queiroz, Bia Arantes, Carlo Porto, Priscila Sol, Dani Gondim, Karin Hils, Eliana Guttman e Lucero nos pap\u00e9is principais. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo novela \u201cCarinha de Anjo\u201d 20\/12: no cap\u00edtulo 283(*) da novela \u201cCarinha de Anjo\u201d, resumo de quarta-feira, 20 de dezembro, Franciely descobre que Leonardo na verdade \u00e9 irm\u00e3o de Estef\u00e2nia e que mentiu para ela. Mais tarde, a Tia Perucas conversa com Franciely e as duas pedem para que Silvestre marque uma consulta para elas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":99331,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[452,379,372,343],"tags":[441],"class_list":{"0":"post-129178","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-carinha-de-anjo","8":"category-novelas","9":"category-sbt","10":"category-televisao","11":"tag-resumo-do-dia","12":"entry","13":"gs-1","14":"gs-odd","15":"gs-even","16":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/carinha_de_anjo_sbt_novela_resumo_capitulo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/129178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=129178"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/129178\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/99331"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=129178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=129178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=129178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}