{"id":12857,"date":"2009-09-28T10:35:46","date_gmt":"2009-09-28T14:35:46","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=12857"},"modified":"2009-09-28T10:35:46","modified_gmt":"2009-09-28T14:35:46","slug":"adobe-anuncia-o-flash-access-2-0","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/adobe-anuncia-o-flash-access-2-0\/12857","title":{"rendered":"Adobe anuncia o Flash Access 2.0"},"content":{"rendered":"<p>Durante a exposi\u00e7\u00e3o IBC 2009, a Adobe Systems Incorporated (Nasdaq:ADBE) anunciou o Adobe\u00ae Flash\u00ae Access 2.0, um componente-chave da Adobe Flash Platform. O Flash Access 2.0, conhecido anteriormente como Adobe Flash Media Rights Management Server, \u00e9 uma solu\u00e7\u00e3o de prote\u00e7\u00e3o de conte\u00fado escalon\u00e1vel e flex\u00edvel que permite a distribui\u00e7\u00e3o e monetiza\u00e7\u00e3o de conte\u00fado premium, capaz de criar novas fontes de renda para publicadores de m\u00eddia.\u00a0<\/p>\n<p>Novidade neste lan\u00e7amento, o conte\u00fado protegido pelo Flash Access 2.0 reproduzir\u00e1 com seguran\u00e7a na pr\u00f3xima vers\u00e3o do software Adobe Flash Player &#8211; o plug-in de navegador para v\u00e1rios sistemas operacionais dispon\u00edvel em mais de 98 por cento dos computadores conectados \u00e0 Internet em todo o mundo. Programado para comercializa\u00e7\u00e3o a partir do in\u00edcio do pr\u00f3ximo ano, o Adobe Flash Access 2.0 oferecer\u00e1 prote\u00e7\u00e3o robusta de conte\u00fado audiovisual, com regras flex\u00edveis de uso para suportar uma grande gama de modelos comerciais, incluindo venda eletr\u00f4nica, loca\u00e7\u00e3o e v\u00eddeo sob demanda, tanto para streaming quanto para download. Acho que devemos tirar j\u00e1 que o evento j\u00e1 passou.<\/p>\n<p>&#8220;Como software N\u00ba 1 de reprodu\u00e7\u00e3o de v\u00eddeo na Web, a Adobe Flash Platform tem permitido a milh\u00f5es de usu\u00e1rios apreciarem conte\u00fado de alta qualidade&#8221;, disse Jim Guerard, vice-presidente e gerente-geral de M\u00eddia Din\u00e2mica da Adobe. &#8220;Com o Adobe Flash Access 2.0, os publicadores de m\u00eddia poder\u00e3o confiar na prote\u00e7\u00e3o robusta de conte\u00fado premium com suporte a novos e emergentes modelos comerciais para proporcionar experi\u00eancia rica e interativa online&#8221;.<\/p>\n<p>Alcance e Flexibilidade Sem Precedentes<\/p>\n<p>Empresas de m\u00eddia continuam lan\u00e7ando novos meios de conectar usu\u00e1rios a conte\u00fado premium via canais de distribui\u00e7\u00e3o online. Para criar modelos comerciais sustent\u00e1veis, essas empresas devem encontrar o equil\u00edbrio certo entre acesso e controle de seus conte\u00fados. O Flash Access 2.0 oferece um modo de combinar o alcance sem precedentes e a interatividade da Adobe Flash Platform (Plataforma Adobe Flash), com seguran\u00e7a robusta e regras de uso flex\u00edveis para que as empresas possam colocar as restri\u00e7\u00f5es necess\u00e1rias, como limitar a exibi\u00e7\u00e3o a um dado per\u00edodo de loca\u00e7\u00e3o.<\/p>\n<p>&#8220;Na Warner Bros., estamos sempre buscando meios inovadores que permitam ao nosso p\u00fablico apreciar v\u00eddeos online&#8221;, disse Darcy Antonellis, presidente de Opera\u00e7\u00f5es T\u00e9cnicas da Warner Bros. &#8220;Damos boas-vindas ao desenvolvimento do Adobe Flash Access, que ajudar\u00e1 a criar novas possibilidades para nossos parceiros atuais e futuros oferecerem conte\u00fado da Warner Bros. de modo cont\u00ednuo e f\u00e1cil com o Adobe Flash Player, ampliando o acesso ao nosso entretenimento online&#8221;.<\/p>\n<p>Empresas e institui\u00e7\u00f5es de ensino tamb\u00e9m podem usar o Flash Access 2.0 para criarem solu\u00e7\u00f5es que atendam suas necessidades de prote\u00e7\u00e3o de conte\u00fado, permitindo distribuir conte\u00fado audiovisual como materiais de treinamento e comunica\u00e7\u00e3o corporativa de modo seguro aos seus funcion\u00e1rios, clientes ou parceiros.<\/p>\n<p>Prote\u00e7\u00e3o Robusta a Conte\u00fado Premium<\/p>\n<p>Usando criptografia padr\u00e3o do setor, o Adobe Flash Access 2.0 oferecer\u00e1 um ambiente robusto para proteger conte\u00fado, de modo que permane\u00e7a seguro contra fraudes ou captura durante todo o seu ciclo de vida \u00fatil. O conte\u00fado pode ser vinculado de modo seguro a um dispositivo individual ou a um dom\u00ednio, que pode representar um domic\u00edlio. O Flash Access 2.0 agora suporta prote\u00e7\u00e3o de sa\u00edda, permitindo aos provedores de conte\u00fado especificar requisitos de prote\u00e7\u00e3o de sa\u00edda anal\u00f3gica e digital, proporcionando seguran\u00e7a adicional contra grava\u00e7\u00e3o n\u00e3o autorizada.<\/p>\n<p>O Flash Access 2.0 suporta distribui\u00e7\u00e3o de conte\u00fado MPEG 4 (H.264) baseado em padr\u00f5es, bem como formato de arquivo FLV atrav\u00e9s de uma variedade de mecanismos de distribui\u00e7\u00e3o, incluindo download progressivo, streaming e download para reprodu\u00e7\u00e3o local. Conte\u00fado protegido tamb\u00e9m pode ser reproduzido em aplica\u00e7\u00f5es ricas para Internet (RIAs) rodando fora do navegador usando o Adobe AIRT. Desenvolvedores podem criar solu\u00e7\u00f5es RIA em sistemas operacionais diversos com o Adobe AIR, que incluem bibliotecas locais de conte\u00fado, gerenciamento avan\u00e7ado de download e interfaces de usu\u00e1rio altamente interativas.<\/p>\n<p>F\u00e1cil Distribui\u00e7\u00e3o e Integra\u00e7\u00e3o<\/p>\n<p>O Adobe Flash Access 2.0 \u00e9 oferecido com um Kit de Desenvolvimento de Software, permitindo a distribui\u00e7\u00e3o em escala e f\u00e1cil integra\u00e7\u00e3o com software e servi\u00e7os existentes, como gerenciamento de pedidos, bancos de dados de assinatura, controle de acesso e Diret\u00f3rios Ativos baseados em LDAP. O Flash Access tamb\u00e9m estar\u00e1 dispon\u00edvel como Software Service (SaaS), atrav\u00e9s de uma variedade de parceiros da AdobeAcho melhor deletar, pois n\u00e3o tenho certeza que estar\u00e1 dispon\u00edvel para o Brasil.<\/p>\n<p>Plataforma N\u00ba 1 para Oferecer V\u00eddeo na Web<\/p>\n<p>A Adobe Flash Platform (Plataforma Adobe Flash) \u00e9 um sistema completo de ferramentas integradas, estruturas, clientes e servidores para o desenvolvimento de aplicativos da Web, conte\u00fado e v\u00eddeos que funcionam consistentemente em v\u00e1rios sistemas operacionais e dispositivos. O Adobe Flash Player est\u00e1 instalado em mais de 98 por cento dos computadores conectados \u00e0 Internet e oferece aproximadamente 80 por cento dos v\u00eddeos na Web em todo o mundo. Os principais broadcasters e empresas de m\u00eddia, incluindo a BBC, Disney.com, HULU e PBS, utilizam a Plataforma Flash para oferecerem v\u00eddeo sob demanda e conte\u00fado de streaming a seus p\u00fablicos em todo o mundo. A tecnologia Flash tamb\u00e9m \u00e9 usada para oferecer eventos online de streaming na MLB.com e DirectTV, e a plataforma opera sites de redes sociais como o YouTube e MySpace.<\/p>\n<p>Disponibilidade<\/p>\n<p>A disponibilidade comercial do Adobe Flash Access est\u00e1 planejada para o primeiro semestre de 2010.<\/p>\n<p>Sobre a Adobe Systems Incorporated<\/p>\n<p>A Adobe revoluciona a forma como o mundo interage com ideias e informa\u00e7\u00f5es &#8211; a qualquer momento, em qualquer lugar e atrav\u00e9s de qualquer m\u00eddia. Visite www.adobe.com.br para obter mais informa\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante a exposi\u00e7\u00e3o IBC 2009, a Adobe Systems Incorporated (Nasdaq:ADBE) anunciou o Adobe\u00ae Flash\u00ae Access 2.0, um componente-chave da Adobe Flash Platform. O Flash Access 2.0, conhecido anteriormente como Adobe Flash Media Rights Management Server, \u00e9 uma solu\u00e7\u00e3o de prote\u00e7\u00e3o de conte\u00fado escalon\u00e1vel e flex\u00edvel que permite a distribui\u00e7\u00e3o e monetiza\u00e7\u00e3o de conte\u00fado premium, capaz [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-12857","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/12857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=12857"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/12857\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=12857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=12857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=12857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}