{"id":128297,"date":"2017-12-08T20:34:27","date_gmt":"2017-12-08T22:34:27","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=128297"},"modified":"2017-12-08T20:34:27","modified_gmt":"2017-12-08T22:34:27","slug":"resumo-novela-sortilegio-11-12-bruno-desiste-de-impugnar-o-testamento","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2017\/resumo-novela-sortilegio-11-12-bruno-desiste-de-impugnar-o-testamento\/128297","title":{"rendered":"Resumo novela \u201cSortil\u00e9gio\u201d 11\/12: Bruno desiste de impugnar o testamento"},"content":{"rendered":"<p> <strong><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-60833\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/sortilegio_novela_resumo_sbt-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/sortilegio_novela_resumo_sbt-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/sortilegio_novela_resumo_sbt-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>Resumo novela \u201cSortil\u00e9gio\u201d 11\/12<\/em><\/strong>: no cap\u00edtulo 041(*) da novela \u201cSortil\u00e9gio\u201d, resumo de segunda-feira, 11 de dezembro, Vit\u00f3ria diz a Maria Jos\u00e9 que n\u00e3o devem perder a f\u00e9. Fernando, fora de si, diz a Alessandro que n\u00e3o quer morrer em uma ilha deserta, confessa que \u00e9 apaixonado por Vit\u00f3ria e que n\u00e3o teve tempo sequer para conquist\u00e1-la. Roberto entrega a Ulisses uma passagem de avi\u00e3o para que v\u00e1 buscar sua namorada em Madri. Raquel descobre o plano de Roberto e tenta impedir que o amante viaje. Raquel sofre um acidente sem consequ\u00eancias. Mary, a secret\u00e1ria de Alessandro, segue K\u00e1tia, e assim Vit\u00f3ria e Maria Jos\u00e9 descobrem que Bruno voltou e v\u00e3o procur\u00e1-lo para saber o que aconteceu com Alessandro e Fernando. <\/p>\n<p>Muito nervosa, Vit\u00f3ria diz ao filho que far\u00e1 uma reuni\u00e3o e toda a verdade vir\u00e1 \u00e0 tona. Maria Jos\u00e9 amea\u00e7a contar tudo que sabe se alguma coisa acontecer com Alessandro. O advogado diz a Bruno que se quiser que o defenda ter\u00e1 que lhe contar toda a verdade, pois Vit\u00f3ria \u00e9 uma mulher muito inteligente e Maria Jos\u00e9 parece muito segura. Furioso, Bruno diz ao advogado que est\u00e1 sendo pago para impugnar o testamento. Roberto diz a Raquel que o acidente n\u00e3o prejudicou o beb\u00ea. Ela responde que independente de quem seja o pai, n\u00e3o quer a crian\u00e7a. <\/p>\n<p>Maria Jos\u00e9 fala a Paula e Felipa que Bruno nega ter estado no mesmo lugar que Alessandro e Fernando. Bruno, ao perceber que Vit\u00f3ria j\u00e1 sabe de tudo e est\u00e1 disposta a contar a todos, amea\u00e7a suicidar-se e consegue seu objetivo, pois Vit\u00f3ria pede a Maria Jos\u00e9 que na reuni\u00e3o n\u00e3o comente nada sobre a viagem. Desesperada, Maria Jos\u00e9 diz que algo ele fez contra Fernando e Alessandro e n\u00e3o \u00e9 justo que saia vitorioso. Bruno desiste de impugnar o testamento. Maria Jos\u00e9 diz a Bruno que sabe que ele matou o irm\u00e3o para ficar com a heran\u00e7a, mas afirma que lutar\u00e1 para que isso n\u00e3o aconte\u00e7a at\u00e9 o fim de seus dias.<\/p>\n<p>(*) edi\u00e7\u00e3o do SBT, Novela \u201cSortil\u00e9gio\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado. <\/p>\n<p>A trama conta uma hist\u00f3ria de enganos e trai\u00e7\u00f5es, onde o \u00f3dio que Bruno sente por seu meio-irm\u00e3o Alessandro, o leva a planejar sua morte s\u00f3 para se tornar herdeiro de sua fortuna. Vit\u00f3ria teve um caso com o amigo de seu marido Samuel, Antonio Lombardo, resultando no nascimento de g\u00eameos: Bruno e Raquel. Antonio tamb\u00e9m teve um filho, Alessandro, com sua esposa Adriana. Depois de seus respectivos c\u00f4njuges morreram, Vit\u00f3ria e Ant\u00f4nio come\u00e7aram um relacionamento e se casaram. No entanto, eles n\u00e3o disseram a seus filhos que eram meio-irm\u00e3os, j\u00e1 que revelaria suas infidelidades. Em vez disso, criaram seus filhos que reconhecerem-se mutuamente como meio-irm\u00e3os. Os anos passam, e Bruno vem a ser um homem irrespons\u00e1vel que n\u00e3o respeita as leis. Alessandro, por outro lado, \u00e9 muito respons\u00e1vel. <\/p>\n<p>Antonio prefere Alessandro a Bruno, e decide que Alessandro deve herdar seu dinheiro quando morrer. Antonio e Vit\u00f3ria v\u00e3o \u00e1 uma reuni\u00e3o na escola de Bruno sobre seu comportamento, e lhe \u00e9 dito que ele foi expulso. Enquanto eles est\u00e3o deixando o local, eles come\u00e7am uma discuss\u00e3o e distra\u00eddo, Antonio prende suas muletas em um buraco. Vit\u00f3ria que est\u00e1 brava com ele por causa de seus argumentos, continua andando e n\u00e3o ajuda o marido. Quando Antonio tenta se libertar, um homem em uma motocicleta se choca contra ele, causando a morte de Antonio. Vit\u00f3ria torna-se novamente vi\u00fava. Algum tempo depois, Fernando, amigo de Alessandro, se apaixona por Vit\u00f3ria, mas seu amor n\u00e3o pode acontecer por causa da diferen\u00e7a de idade. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo novela \u201cSortil\u00e9gio\u201d 11\/12: no cap\u00edtulo 041(*) da novela \u201cSortil\u00e9gio\u201d, resumo de segunda-feira, 11 de dezembro, Vit\u00f3ria diz a Maria Jos\u00e9 que n\u00e3o devem perder a f\u00e9. Fernando, fora de si, diz a Alessandro que n\u00e3o quer morrer em uma ilha deserta, confessa que \u00e9 apaixonado por Vit\u00f3ria e que n\u00e3o teve tempo sequer para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":60833,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[379,372,343],"tags":[441],"class_list":{"0":"post-128297","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-sbt","9":"category-televisao","10":"tag-resumo-do-dia","11":"entry","12":"gs-1","13":"gs-odd","14":"gs-even","15":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/sortilegio_novela_resumo_sbt.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/128297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=128297"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/128297\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/60833"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=128297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=128297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=128297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}