{"id":12271,"date":"2009-09-18T19:08:42","date_gmt":"2009-09-18T23:08:42","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=12271"},"modified":"2009-09-18T19:08:42","modified_gmt":"2009-09-18T23:08:42","slug":"previsao-do-tempo-na-regiao-nordeste-de-19-a-2109","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/previsao-do-tempo-na-regiao-nordeste-de-19-a-2109\/12271","title":{"rendered":"Previs\u00e3o do tempo na Regi\u00e3o Nordeste de 19 a 21\/09"},"content":{"rendered":"<p><strong>Previs\u00e3o do tempo na Regi\u00e3o Nordeste<\/strong>\u00a019\/09\/2009: No norte da Regi\u00e3o: sol com nebulosidade vari\u00e1vel e possibilidade de pancadas de chuva. Nas demais \u00e1reas da Regi\u00e3o: sol entre poucas nuvens. As temperaturas seguir\u00e3o est\u00e1veis. Temperaturas m\u00e1xima: 39C no centro do PI. Temperaturas m\u00ednima: 14C no sul da BA. \u00a0Tend\u00eancia 20 e 21\/09: No litoral do RN, da PB e de PE: sol com nebulosidade vari\u00e1vel e pancadas de chuva. Nas demais \u00e1reas do RN, da PB e de PE: nublado com chuva isolada. Em boa parte do MA, de PI e do CE: sol com nebulosidade vari\u00e1vel com possibilidade de pancadas de chuva. Nas demais \u00e1reas da Regi\u00e3o: sol entre poucas nuvens. As temperaturas seguir\u00e3o est\u00e1veis. Nos pr\u00f3ximos dois dias n\u00e3o h\u00e1 grande mudan\u00e7a no tempo.<\/p>\n<p>O Centro de Previs\u00e3o de Tempo e Estudos Clim\u00e1ticos \u2013 CPTEC, do Instituto Nacional de Pesquisas Espaciais \u2013 INPE \u00e9 o passaporte do Brasil para o primeiro mundo das previs\u00f5es meteorol\u00f3gicas. Os supercomputadores vetoriais SX-6 e SX-4 fabricados pela NEC Corporation do Jap\u00e3o, possuem capacidade de processar at\u00e9 768 bilh\u00f5es e 16 bilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo respectivamente. Recentemente adquirido da \u201cNEC Corporation do Jap\u00e3o\u201d um cluster com 1100 processadores fabricado pela \u201cSUN Microsystem\u201d com a capacidade de processar at\u00e9 5.7 trilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo.<\/p>\n<p>Isso significa possibilidade de utilizar modelos num\u00e9ricos para simula\u00e7\u00e3o de tempo e clima, integrando informa\u00e7\u00f5es atmosf\u00e9ricas e oce\u00e2nicas. O resultado disso s\u00e3o previs\u00f5es de tempo confi\u00e1veis, para todo o pa\u00eds.\u00a0<\/p>\n<p>CPTEC\/INPE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previs\u00e3o do tempo na Regi\u00e3o Nordeste\u00a019\/09\/2009: No norte da Regi\u00e3o: sol com nebulosidade vari\u00e1vel e possibilidade de pancadas de chuva. Nas demais \u00e1reas da Regi\u00e3o: sol entre poucas nuvens. As temperaturas seguir\u00e3o est\u00e1veis. Temperaturas m\u00e1xima: 39C no centro do PI. Temperaturas m\u00ednima: 14C no sul da BA. \u00a0Tend\u00eancia 20 e 21\/09: No litoral do RN, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,327],"tags":[],"class_list":{"0":"post-12271","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"category-clima","8":"entry","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/12271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=12271"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/12271\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=12271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=12271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=12271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}