{"id":122077,"date":"2017-09-27T00:20:47","date_gmt":"2017-09-27T03:20:47","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=122077"},"modified":"2017-09-26T15:41:18","modified_gmt":"2017-09-26T18:41:18","slug":"impactos-da-elevacao-das-mares-em-santos-ja-sao-visiveis","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2017\/impactos-da-elevacao-das-mares-em-santos-ja-sao-visiveis\/122077","title":{"rendered":"Impactos da eleva\u00e7\u00e3o das mar\u00e9s em Santos j\u00e1 s\u00e3o vis\u00edveis"},"content":{"rendered":"<p> Ag\u00eancia FAPESP\u00a0\u2013 Os estudos do Projeto Metr\u00f3pole, com\u00a0, demonstram que a cidade de <strong><em>Santos<\/em><\/strong>, no Estado de S\u00e3o Paulo, j\u00e1 est\u00e1 exposta a tempestades, eros\u00e3o e intrus\u00e3o de \u00e1gua salgada, de acordo com a Assessoria de Comunica\u00e7\u00e3o do Centro Nacional de Monitoramento e Alertas de Desastres Naturais (Cemaden).<\/p>\n<p>H\u00e1 uma tend\u00eancia das altera\u00e7\u00f5es clim\u00e1ticas e a subida do n\u00edvel do mar intensificarem esses riscos, conforme pesquisa coordenada pelo climatologista Jos\u00e9 Marengo, do Cemaden.<\/p>\n<p>Esses impactos foram observados tamb\u00e9m em Broward, nos Estados Unidos, e Selsey, na Inglaterra. Iniciativa internacional com pesquisadores brasileiros, norte-americanos e ingleses vem desenvolvendo, desde 2013, estudos sobre adapta\u00e7\u00e3o \u00e0s mudan\u00e7as clim\u00e1ticas em \u00e1reas costeiras.<\/p>\n<p>Os dados da pesquisa fazem proje\u00e7\u00f5es dos impactos associados \u00e0 eleva\u00e7\u00e3o da temperatura oce\u00e2nica e chuvas extremas, al\u00e9m do aumento do n\u00edvel do mar e aumento na frequ\u00eancia e na intensidade das tempestades. Esses fatores podem gerar deslizamentos de terra, enchentes urbanas e contamina\u00e7\u00e3o das \u00e1guas subterr\u00e2neas. Na situa\u00e7\u00e3o atual, as \u00e1reas suscet\u00edveis \u00e0 inunda\u00e7\u00e3o j\u00e1 apresentam problemas de drenagem.<\/p>\n<p>Na cidade de Santos, no litoral paulista, os estudos projetam que as mudan\u00e7as clim\u00e1ticas provocar\u00e3o a subida do n\u00edvel do mar em pelo menos 18 cent\u00edmetros at\u00e9 2050, podendo chegar at\u00e9 45 cent\u00edmetros em 2100. Essa eleva\u00e7\u00e3o do n\u00edvel do mar poder\u00e1 chegar a dois metros, durante a ocorr\u00eancia de mar\u00e9s altas, tempestades e as ressacas.<\/p>\n<p>\u201cAs adapta\u00e7\u00f5es ser\u00e3o necess\u00e1rias, n\u00e3o h\u00e1 como escapar. E n\u00e3o estamos falando sobre mudan\u00e7as do clima em um futuro distante \u2013 \u00e9 preciso entrar em a\u00e7\u00e3o agora\u201d, afirmou o pesquisador Marengo.<\/p>\n<p>Medidas de minimiza\u00e7\u00e3o de impacto<\/p>\n<p>Entre as medidas estrat\u00e9gicas indicadas \u00e0s cidades costeiras para a gest\u00e3o da adapta\u00e7\u00e3o, podem-se destacar o monitoramento da mudan\u00e7a do clima e as avalia\u00e7\u00f5es dos desastres socioambientais, para adequar a situa\u00e7\u00e3o das mudan\u00e7as ocasionadas ao longo do tempo.<\/p>\n<p>O trabalho cient\u00edfico aponta dois caminhos para a prepara\u00e7\u00e3o e diminui\u00e7\u00e3o dos impactos das mudan\u00e7as clim\u00e1ticas nas \u00e1reas costeiras: as medidas proativas e planejadas para preservar e proteger os recursos \u2013 antecipando-se aos impactos (adapta\u00e7\u00e3o planejada) \u2013 e as medidas reativas\/emergenciais, implementadas ap\u00f3s o impacto das mudan\u00e7as clim\u00e1ticas.<\/p>\n<p>O Projeto Metr\u00f3pole \u00e9 uma coprodu\u00e7\u00e3o entre a comunidade cient\u00edfica, os tomadores de decis\u00f5es e a popula\u00e7\u00e3o. Santos foi escolhida para o projeto, segundo Marengo, porque tem os dados mais completos sobre varia\u00e7\u00f5es de mar\u00e9s e o georreferenciamento mais preciso entre as cidades litor\u00e2neas. Os m\u00e9todos utilizados podem ser replicados em qualquer cidade da costa brasileira.<\/p>\n<p>A pesquisa aplicada desenvolvida nos \u00faltimos quatro anos faz uma avalia\u00e7\u00e3o conjunta sobre poss\u00edveis impactos da eleva\u00e7\u00e3o do n\u00edvel do mar, extremos de chuva e tempestades na frequ\u00eancia e intensidade das inunda\u00e7\u00f5es costeiras que afetam a Ponta da Praia, no munic\u00edpio de Santos. Segundo os dados cient\u00edficos, estes impactos podem aumentar no futuro.<\/p>\n<p>Mais informa\u00e7\u00f5es:\u00a0.<\/p>\n<p>Outras informa\u00e7\u00f5es sobre o Projeto Metr\u00f3pole est\u00e3o dispon\u00edveis nas reportagens publicadas pela Ag\u00eancia FAPESP:\u00a0,\u00a0\u00a0e\u00a0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ag\u00eancia FAPESP\u00a0\u2013 Os estudos do Projeto Metr\u00f3pole, com\u00a0, demonstram que a cidade de Santos, no Estado de S\u00e3o Paulo, j\u00e1 est\u00e1 exposta a tempestades, eros\u00e3o e intrus\u00e3o de \u00e1gua salgada, de acordo com a Assessoria de Comunica\u00e7\u00e3o do Centro Nacional de Monitoramento e Alertas de Desastres Naturais (Cemaden). H\u00e1 uma tend\u00eancia das altera\u00e7\u00f5es clim\u00e1ticas e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":41101,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-122077","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"entry","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/praia-balneario.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/122077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=122077"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/122077\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/41101"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=122077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=122077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=122077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}