{"id":117760,"date":"2017-07-26T16:41:16","date_gmt":"2017-07-26T19:41:16","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=117760"},"modified":"2017-07-25T15:36:55","modified_gmt":"2017-07-25T18:36:55","slug":"novela-vidas-em-jogo-resumo-2707-lucas-conversa-com-sua-alucinacao","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2017\/novela-vidas-em-jogo-resumo-2707-lucas-conversa-com-sua-alucinacao\/117760","title":{"rendered":"Novela \u201cVidas em Jogo\u201d resumo 27\/07: Lucas conversa com sua alucina\u00e7\u00e3o"},"content":{"rendered":"<p> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-34838\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/vidas-em-jogo-resumo-novela-rede-record-capitulos-150x96.jpg\" alt=\"vidas em jogo resumo novela rede record capitulos\" width=\"150\" height=\"96\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/vidas-em-jogo-resumo-novela-rede-record-capitulos-150x96.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/vidas-em-jogo-resumo-novela-rede-record-capitulos-250x161.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/vidas-em-jogo-resumo-novela-rede-record-capitulos.jpg 301w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Novela \u201cVidas em Jogo\u201d resumo 27\/07<\/em><\/strong>: no capitulo 223 (*) da novela \u201cVidas em Jogo\u201d, quinta-feira, 27 de julho, Welligton decide fugir. Carlos aparece na sala e corre para alcan\u00e7ar o filho. Na portaria do pr\u00e9dio, Jos\u00e9, Marizete, Marta e Fabinho se preparam para iniciar as buscas por pistas sobre o paradeiro de Regina. Welligton encontra o grupo e rouba a bolsa de Marizete. Jos\u00e9 e Fabinho correm para capturar o jogador. Na persegui\u00e7\u00e3o, o personal stylist cai, mas Jos\u00e9 continua correndo. Welligton pula o muro e o porteiro desiste. Carlos aparece e explica que o jogador fumou crack. Ele decide pegar o carro para circular pela \u00e1rea. Lucas conversa com sua alucina\u00e7\u00e3o para decidir se matar\u00e1 seus ref\u00e9ns. Cleber e Regina ficam assustados. Ele diz para a dupla que s\u00f3 n\u00e3o os matar\u00e1 porque Andrea pediu. Raimundo diz a Zizi que Lucas est\u00e1 perturbado. <\/p>\n<p>Dentro de uma limousine de cor berrante, Marizete chega ao local em que o corpo de Elton foi encontrado. Um policial se aproxima e o grupo come\u00e7a a interrog\u00e1-lo, tentando descobrir algumas pistas. O grupo \u00e9 expulso, mas antes que saiam, Fabinho fotografa o carro incinerado e o local do acidente. A limousine se afasta, mas o grupo continua inspecionando a \u00e1rea. Lucas observa, espionando o quarteto. Marizete quase o v\u00ea. Severino pede que Divina descubra se Margarida \u00e9 a assassina do bol\u00e3o. As duas conversam, mas a milion\u00e1ria logo percebe as inten\u00e7\u00f5es de Divina e a expulsa do quarto. <\/p>\n<p>Daniel consegue convencer Jaqueline de que Ernesto deve ser aceito como padrasto, por\u00e9m, usa como argumento um plano para afast\u00e1-lo de Divina para sempre. Welligton troca a bolsa de Marizete por drogas. Procurando pelo filho adotivo, Carlos \u00e9 atacado por alguns drogados. Ele encontra a mulher que acompanhava Welligton, mas durante a confus\u00e3o, ela foge. Sozinho, o milion\u00e1rio cai de joelhos e come\u00e7a a chorar. Lucas e Juliana discutem mais uma vez. Ela decide sair de casa. \u00c0 pedido de Ernesto, Divina liga para Daniel e o chama para ir \u00e0 praia junto com Jaqueline. O convite \u00e9 aceito, deixando Severino desconfort\u00e1vel. Pressionada por Valdisnei, Margarida confessa que sabia de todas as arma\u00e7\u00f5es de Elton.<\/p>\n<p>(*) edi\u00e7\u00e3o da Rede Record, Novela \u201cVidas em Jogo\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela \u201cVidas em Jogo\u201d resumo 27\/07: no capitulo 223 (*) da novela \u201cVidas em Jogo\u201d, quinta-feira, 27 de julho, Welligton decide fugir. Carlos aparece na sala e corre para alcan\u00e7ar o filho. Na portaria do pr\u00e9dio, Jos\u00e9, Marizete, Marta e Fabinho se preparam para iniciar as buscas por pistas sobre o paradeiro de Regina. Welligton [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":34838,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[379,371,343],"tags":[441],"class_list":{"0":"post-117760","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-rede-record","9":"category-televisao","10":"tag-resumo-do-dia","11":"entry","12":"gs-1","13":"gs-odd","14":"gs-even","15":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/vidas-em-jogo-resumo-novela-rede-record-capitulos.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/117760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=117760"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/117760\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/34838"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=117760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=117760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=117760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}