{"id":117375,"date":"2017-07-20T00:07:24","date_gmt":"2017-07-20T03:07:24","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=117375"},"modified":"2017-07-19T14:00:20","modified_gmt":"2017-07-19T17:00:20","slug":"virus-oropouche-pode-emergir-e-causar-problemas-de-saude-publica-no-brasil","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2017\/virus-oropouche-pode-emergir-e-causar-problemas-de-saude-publica-no-brasil\/117375","title":{"rendered":"V\u00edrus oropouche pode emergir e causar problemas de sa\u00fade p\u00fablica no Brasil"},"content":{"rendered":"<p> Elton Alisson, de Belo Horizonte (MG) | Ag\u00eancia FAPESP\u00a0\u2013 Depois da epidemia de Zika, iniciada em 2015, e do surto de febre amarela, no come\u00e7o deste ano, o Brasil corre o s\u00e9rio risco de ser afligido por outro v\u00edrus de ampla distribui\u00e7\u00e3o nas Am\u00e9ricas do Sul e Central e no Caribe, que se adaptou ao meio urbano e tem chegado cada vez mais pr\u00f3ximo das grandes cidades brasileiras. \u00c9 o <em><strong>oropouche<\/strong><\/em> \u2013 um arbov\u00edrus (v\u00edrus transmitido por um mosquito, como o Zika e o da febre amarela), que causa febre aguda e, eventualmente, meningite e inflama\u00e7\u00e3o do enc\u00e9falo e das meninges (meningocefalite).<\/p>\n<p>O alerta foi feito por Luiz Tadeu Moraes Figueiredo, professor da Faculdade de Medicina de Ribeir\u00e3o Preto da Universidade de S\u00e3o Paulo (FMRP-USP), durante palestra sobre v\u00edrus emergentes na 69\u00aa Reuni\u00e3o Anual da Sociedade Brasileira para o Progresso da Ci\u00eancia (SBPC).<\/p>\n<p>Com o tema \u201cInova\u00e7\u00e3o \u2013 Diversidade \u2013 Transforma\u00e7\u00f5es\u201d, o evento, que ocorre at\u00e9 o pr\u00f3ximo s\u00e1bado (22\/07) no campus Pampulha da Universidade Federal de Minas Gerais (UFMG), re\u00fane pesquisadores do Brasil e do exterior e gestores do sistema nacional de ci\u00eancia e tecnologia.<\/p>\n<p>\u201cO oropouche \u00e9 um v\u00edrus que potencialmente pode emergir a qualquer momento e causar um s\u00e9rio problema de sa\u00fade p\u00fablica no Brasil\u201d, disse Figueiredo durante o evento.<\/p>\n<p>De acordo com o pesquisador, que coordena um  apoiado pela FAPESP, h\u00e1 mais de 500 mil casos relatados no pa\u00eds nas \u00faltimas d\u00e9cadas de febre do oropouche \u2013 como \u00e9 conhecida a doen\u00e7a causada pelo v\u00edrus.<\/p>\n<p>Esse n\u00famero, contudo, tende a subir, uma vez que o v\u00edrus, transmitido pelo mosquito Culicoides paraensis \u2013 conhecido popularmente como maruim ou borrachudo \u2013, antes restrito aos pequenos vilarejos da Amaz\u00f4nia, tem se alastrado e chegado \u00e0s grandes cidades do pa\u00eds, ponderou Figueiredo.<\/p>\n<p>\u201cO oropouche \u00e9 um v\u00edrus que tem um grande potencial de emerg\u00eancia, porque o Culicoides paraensis est\u00e1 distribu\u00eddo por todo o continente americano. O v\u00edrus pode sair da regi\u00e3o amaz\u00f4nica e do planalto central e chegar \u00e0s regi\u00f5es mais povoadas do Brasil\u201d, apontou.<\/p>\n<p>Aumento de casos<\/p>\n<p>O n\u00famero de casos de febre oropouche tamb\u00e9m tem se tornado mais frequente em \u00e1reas urbanas n\u00e3o s\u00f3 no Brasil, como no Peru e pa\u00edses do Caribe.<\/p>\n<p>No Brasil, o v\u00edrus j\u00e1 foi isolado em aves no Rio Grande do Sul, em um macaco sagui em Minas Gerais e foi detectada a presen\u00e7a de anticorpos neutralizantes (que se ligam ao v\u00edrus e sinalizam ao sistema imune que destrua aquele corpo estranho e o impe\u00e7am de completar a infec\u00e7\u00e3o com sucesso) em primatas em Goi\u00e2nia.<\/p>\n<p>\u201cFizemos recentemente, em parceria com o professor Eurico Arruda [do Departamento de Biologia Celular da FMRP-USP)]\u00a0o diagn\u00f3stico de um paciente de Ilh\u00e9us, na Bahia, com febre oropouche. Isso mostra que o v\u00edrus tem circulado pelo pa\u00eds\u201d, avaliou.<\/p>\n<p>Os pesquisadores da institui\u00e7\u00e3o j\u00e1 haviam diagnosticado, em 2002, 128 pessoas infectadas pelo v\u00edrus oropouche em Manaus (AM).<\/p>\n<p>Os pacientes apresentavam os sintomas t\u00edpicos da infec\u00e7\u00e3o, como febre aguda, dores articulares, de cabe\u00e7a e atr\u00e1s dos olhos.<\/p>\n<p>Tr\u00eas deles desenvolveram infec\u00e7\u00e3o no sistema nervoso central. \u201cO v\u00edrus foi encontrado no l\u00edquor cefalorraquidiano desses pacientes\u201d, disse Figueiredo.<\/p>\n<p>O que chamou a aten\u00e7\u00e3o dos pesquisadores \u00e9 que um desses tr\u00eas pacientes tinha neurocisticercose \u2013 infec\u00e7\u00e3o do sistema nervoso central pela larva da t\u00eania do porco (Taenia solium) \u2013 e outro tinha Aids.<\/p>\n<p>\u201cIsso mostra que algumas doen\u00e7as de base ou imunodepress\u00e3o [defici\u00eancia do sistema imune observada durante doen\u00e7as, como o c\u00e2ncer e a Aids] podem facilitar que o v\u00edrus chegue ao sistema nervoso central\u201d, apontou o pesquisador.<\/p>\n<p>\u201c\u00c9 algo que quase ningu\u00e9m pensa ao tratar de uma arborvirose e \u00e9 preciso considerar essa possibilidade\u201d, afirmou.<\/p>\n<p>Os 128 pacientes infectados com oropouche em Manaus tinham diagn\u00f3stico cl\u00ednico de dengue, uma vez que os sintomas da doen\u00e7a s\u00e3o parecidos com os da febre oropouche.<\/p>\n<p>Por essa raz\u00e3o, os pesquisadores da FMRP-USP e de outras institui\u00e7\u00f5es, como a Fiocruz, come\u00e7aram a chamar a aten\u00e7\u00e3o para o fato de que o v\u00edrus oropouche pode ser a causa de muitos casos suspeitos de dengue no Brasil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elton Alisson, de Belo Horizonte (MG) | Ag\u00eancia FAPESP\u00a0\u2013 Depois da epidemia de Zika, iniciada em 2015, e do surto de febre amarela, no come\u00e7o deste ano, o Brasil corre o s\u00e9rio risco de ser afligido por outro v\u00edrus de ampla distribui\u00e7\u00e3o nas Am\u00e9ricas do Sul e Central e no Caribe, que se adaptou ao [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":40847,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,5],"tags":[],"class_list":{"0":"post-117375","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-saude-e-vida","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/dengue-combate.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/117375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=117375"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/117375\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/40847"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=117375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=117375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=117375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}