{"id":10551,"date":"2009-09-02T19:00:43","date_gmt":"2009-09-02T23:00:43","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=10551"},"modified":"2009-09-02T19:00:43","modified_gmt":"2009-09-02T23:00:43","slug":"ufpa-sedia-lancamento-do-programa-musibraille","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/ufpa-sedia-lancamento-do-programa-musibraille\/10551","title":{"rendered":"UFPA sedia lan\u00e7amento do Programa Musibraille"},"content":{"rendered":"<p>Os estudantes e <strong>m\u00fasicos com defici\u00eancia visual<\/strong> j\u00e1 podem usufruir de uma ferramenta adequada para a aprendizagem musical. Nesta quarta-feira (dia 2), o\u00a0<em>software<\/em> Musibraille ser\u00e1 lan\u00e7ado, oficialmente, em Bel\u00e9m, com o objetivo principal de disponibilizar um programa em portugu\u00eas que transcreva partituras para o sistema de escrita t\u00e1til (o\u00a0<em>Braille<\/em>). O lan\u00e7amento acontecer\u00e1 na Universidade Federal do Par\u00e1 (UFPA) e abranger\u00e1 uma oficina de capacita\u00e7\u00e3o de tr\u00eas dias, voltada, principalmente, aos profissionais de educa\u00e7\u00e3o musical para trabalhar com os alunos cegos por meio do\u00a0<em>software<\/em>.<br \/>\nFinanciado pelo Programa Petrobras Cultural 2006\/2007, o Musibraille \u00e9 um projeto da professora Dolores Tom\u00e9, da Escola de M\u00fasica de Bras\u00edlia, com o professor Ant\u00f4nio Borges, do N\u00facleo de Computa\u00e7\u00e3o Eletr\u00f4nica da Universidade Federal do Rio de Janeiro. A ideia do\u00a0<em>software<\/em> surgiu devido \u00e0 car\u00eancia, no Brasil, de programas e de pessoas que trabalhem com a t\u00e9cnica da Musicografia\u00a0<em>Braille<\/em>, que transcreve um texto musical de qualquer complexidade para a forma t\u00e1til, sendo facilmente assimilado pelos deficientes visuais.<br \/>\nPara a professora Dolores Tom\u00e9, a uni\u00e3o da tecnologia de computa\u00e7\u00e3o com a t\u00e9cnica da Musicografia\u00a0<em>Braille<\/em> \u00e9 fundamental para garantir a inclus\u00e3o social dos portadores de defici\u00eancia visual. \u201cQueremos, com este projeto, dar para pessoas cegas a oportunidade de terem as mesmas ferramentas das pessoas com vis\u00e3o normal, lendo partituras, escrevendo, compondo e, mais do que tudo, tendo o ingresso nas universidades, faculdades e conservat\u00f3rios de m\u00fasica com igualdade de oportunidades profissionais&#8221;, esclarece a professora.<\/p>\n<p>Na UFPA e nas outras universidades, esse projeto est\u00e1 em um contexto promissor e necess\u00e1rio para os educadores, pois, segundo a professora Val\u00e9ria Marques, do Curso de Licenciatura Plena em M\u00fasica, da UFPA, \u201ca partir da promulga\u00e7\u00e3o da Lei Federal N.11.769\/2008, que torna obrigat\u00f3rio o ensino de m\u00fasica em todos os n\u00edveis da educa\u00e7\u00e3o b\u00e1sica a partir de 2011, temos que assumir a responsabilidade pela prepara\u00e7\u00e3o de nossos alunos para um campo de trabalho em expans\u00e3o e que tem como caracter\u00edstica a diversidade\u201d.<br \/>\nAl\u00e9m de promover a capacita\u00e7\u00e3o do\u00a0<em>software<\/em><em> <\/em>por todo o Brasil e possibilitar a inclus\u00e3o dos deficientes visuais no mercado, o projeto pretende manter em seu site\u00a0 uma biblioteca virtual de m\u00fasicas nacionais e internacionais preparadas para impress\u00e3o em\u00a0<em>Braille<\/em>.<br \/>\nA capacita\u00e7\u00e3o que acontecer\u00e1 na UFPA \u00e9 gratuita e, para participar, basta preencher a ficha de inscri\u00e7\u00e3o e enviar para o\u00a0<em>e-mail<\/em> (<a href=\"mailto:darlenelima@yahoo.com.br\" target=\"_blank\">darlenelima@yahoo.com.br<\/a>). O\u00a0<em>software<\/em> Musibraille ser\u00e1 distribu\u00eddo para os participantes da oficina, al\u00e9m de estar dispon\u00edvel para\u00a0<em>download<\/em> gratuito no<em> <\/em><em>site<\/em><em> <\/em>do projeto.<\/p>\n<p><strong>Servi\u00e7o:<\/strong><\/p>\n<p>Lan\u00e7amento do\u00a0<em>software<\/em><em> <\/em>Musibraille<br \/>\nRealiza\u00e7\u00e3o: nesta quarta-feira, dia 2, das 9h \u00e0s 12h<br \/>\nLocal: Audit\u00f3rio Setorial B\u00e1sico I da UFPA (em frente ao Instituto de Ci\u00eancias Biol\u00f3gicas &#8211; ICB)<br \/>\nOficina para capacita\u00e7\u00e3o do\u00a0<em>software<\/em> Musibraille<br \/>\nRealiza\u00e7\u00e3o: dia 02, das 14h \u00e0s 17h30<br \/>\nLocal: Laborat\u00f3rio de Inform\u00e1tica do Instituto de Ci\u00eancias Naturais e Exatas (ICEN -2\u00ba andar) da UFPA<br \/>\nDias 3 e 4, das 8h30 \u00e0s 12h e das 14h \u00e0s 17h30<br \/>\nLocal: Laborat\u00f3rio de Inform\u00e1tica do Instituto de Geoci\u00eancias (IG \u2013 T\u00e9rreo) da UFPA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os estudantes e m\u00fasicos com defici\u00eancia visual j\u00e1 podem usufruir de uma ferramenta adequada para a aprendizagem musical. Nesta quarta-feira (dia 2), o\u00a0software Musibraille ser\u00e1 lan\u00e7ado, oficialmente, em Bel\u00e9m, com o objetivo principal de disponibilizar um programa em portugu\u00eas que transcreva partituras para o sistema de escrita t\u00e1til (o\u00a0Braille). O lan\u00e7amento acontecer\u00e1 na Universidade Federal [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":{"0":"post-10551","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-saude-e-vida","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/10551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=10551"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/10551\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=10551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=10551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=10551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}