{"id":104345,"date":"2017-01-12T20:55:35","date_gmt":"2017-01-12T22:55:35","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=104345"},"modified":"2017-01-12T19:33:08","modified_gmt":"2017-01-12T21:33:08","slug":"novela-carinha-de-anjo-resumo-1301-gustavo-percebe-que-despertou-a-paixao-de-cecilia","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2017\/novela-carinha-de-anjo-resumo-1301-gustavo-percebe-que-despertou-a-paixao-de-cecilia\/104345","title":{"rendered":"Novela \u201cCarinha de Anjo\u201d resumo 13\/01: Gustavo defende Cec\u00edlia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-99331\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/carinha_de_anjo_sbt_novela_resumo_capitulo-150x112.jpg\" alt=\"carinha_de_anjo_sbt_novela_resumo_capitulo\" width=\"150\" height=\"112\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/carinha_de_anjo_sbt_novela_resumo_capitulo-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/carinha_de_anjo_sbt_novela_resumo_capitulo-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Novela \u201cCarinha de Anjo\u201d resumo 13\/01<\/em><\/strong>:\u00a0Madre Superiora diz para Padre Miguel que Cec\u00edlia vai ser transferida para um col\u00e9gio bem longe. Este conta para a Tia Perucas sobre a decis\u00e3o da Madre Superiora. A transfer\u00eancia vai ocorrer dentro de uma semana, Cec\u00edlia chora e pede para que a Madre lhe deixe ficar perto de Dulce Maria nesses \u00faltimos dias. Gustavo quer ajudar Cec\u00edlia e resolve, junto com a Tia Perucas, ir at\u00e9 o col\u00e9gio conversar com a Madre Superiora, que \u00e9 r\u00edspida. Gustavo percebe que despertou a paix\u00e3o de Cec\u00edlia. <\/p>\n<p>No cap\u00edtulo 040(*), novela \u201cCarinha de Anjo\u201d, sexta-feira, 13 de janeiro \u2013 Dulce Maria sonha com a m\u00e3e, Tereza. Rosana vai at\u00e9 a delegacia falar com Peixoto e fazer a den\u00fancia contra Fl\u00e1vio apresentando a foto que Em\u00edlio fez como prova da rouba dos computadores.<\/p>\n<p>Madre Superiora diz para Padre Miguel que Cec\u00edlia ser\u00e1 transferida para um col\u00e9gio bem longe. Gustavo termina o noivado com Nicole. Padre Miguel conta para a Tia Perucas sobre a decis\u00e3o da Madre Superiora. Fl\u00e1vio fica irritado, Haydee chora e Nicole n\u00e3o sabe o que fazer com o fim do noivado.<\/p>\n<p>Madre Superiora avisa que em uma semana Cec\u00edlia ser\u00e1 transferida para o novo col\u00e9gio. Cec\u00edlia chora e pede para que a Madre lhe deixe ficar perto de Dulce Maria nesses \u00faltimos dias. Gustavo quer ajudar Cec\u00edlia. Tia Perucas e Gustavo v\u00e3o at\u00e9 o col\u00e9gio conversar com a Madre Superiora, que \u00e9 r\u00edspida. Diana conversa com Cec\u00edlia. Gustavo percebe que despertou a peix\u00e3o de Cec\u00edlia.<\/p>\n<p>(*) edi\u00e7\u00e3o do SBT, Novela \u201cCarinha de Anjo\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela \u201cCarinha de Anjo\u201d resumo 13\/01:\u00a0Madre Superiora diz para Padre Miguel que Cec\u00edlia vai ser transferida para um col\u00e9gio bem longe. Este conta para a Tia Perucas sobre a decis\u00e3o da Madre Superiora. A transfer\u00eancia vai ocorrer dentro de uma semana, Cec\u00edlia chora e pede para que a Madre lhe deixe ficar perto de Dulce [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":99331,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[452,379,372,343],"tags":[441],"class_list":{"0":"post-104345","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-carinha-de-anjo","8":"category-novelas","9":"category-sbt","10":"category-televisao","11":"tag-resumo-do-dia","12":"entry","13":"gs-1","14":"gs-odd","15":"gs-even","16":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/carinha_de_anjo_sbt_novela_resumo_capitulo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/104345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=104345"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/104345\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/99331"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=104345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=104345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=104345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}