{"id":10123,"date":"2009-08-30T10:59:08","date_gmt":"2009-08-30T14:59:08","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=10123"},"modified":"2009-08-30T10:59:08","modified_gmt":"2009-08-30T14:59:08","slug":"mei-mais-6-estados-incluidos-na-formalizacao-ei-em-setembro","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/mei-mais-6-estados-incluidos-na-formalizacao-ei-em-setembro\/10123","title":{"rendered":"MEI &#8211; Mais 6 estados inclu\u00eddos na formaliza\u00e7\u00e3o EI em setembro"},"content":{"rendered":"<p>MEI &#8211; Os estados do Cear\u00e1, Esp\u00edrito Santo, Paran\u00e1, Rio Grande do Sul, Rond\u00f4nia e Santa Catarina ser\u00e3o inclu\u00eddos no Empreendedor Individual (EI), na primeira semana de setembro. O an\u00fancio foi feito secret\u00e1rio de Com\u00e9rcio e Servi\u00e7os (SCS) do Minist\u00e9rio do Desenvolvimento, Ind\u00fastria e Com\u00e9rcio Exterior (MDIC), Edson Lupatini, nesta quinta-feira (27\/8), em Bras\u00edlia, durante a 15\u00aa Reuni\u00e3o Plen\u00e1ria do F\u00f3rum Permanente das Microempresas e Empresas de Pequeno Porte.<\/p>\n<p>Em vigor desde 1\u00ba de julho, o EI permite a legitima\u00e7\u00e3o das atividades de empreendedores com faturamento anual de at\u00e9 R$ 36 mil. Atualmente, conta com a ades\u00e3o de Distrito Federal, S\u00e3o Paulo, Rio de Janeiro e Minas Gerais. Os demais estados ser\u00e3o inclu\u00eddos nos pr\u00f3ximos meses.<\/p>\n<p>O cronograma est\u00e1 sendo definido pelo Comite Gestor da Rede Nacional para a Simplifica\u00e7\u00e3o do Registro e Legaliza\u00e7\u00e3o de Empresas e Neg\u00f3cios (Redesim), cujo presidente \u00e9 o ministro do MDIC, Miguel Jorge.<\/p>\n<p>Novo regimento do F\u00f3rum Permanente das MPEs<\/p>\n<p>Organizado semestralmente pela Secretaria de Com\u00e9rcio e Servi\u00e7os do MDIC, a 15\u00ba edi\u00e7\u00e3o do evento teve como temas o novo regimento interno e o cronograma de trabalho dos comit\u00eas tem\u00e1ticos do F\u00f3rum, a implementa\u00e7\u00e3o do Empreendedor Individual (EI) nos estados, o desenvolvimento da Redesim e a Pol\u00edtica de Desenvolvimento Produtivo (PDP).<\/p>\n<p>O secret\u00e1rio de Com\u00e9rcio e Servi\u00e7os, Edson Lupatini, apresentou o novo regimento do F\u00f3rum, destacando que as altera\u00e7\u00f5es no documento visam estimular a intera\u00e7\u00e3o entre a Secretaria T\u00e9cnica \u2013 presidida pelo MDIC &#8211; e os Comit\u00eas Tem\u00e1ticos, formados por entidades da iniciativa privada de representa\u00e7\u00e3o nacional e Governo. \u201cOutro objetivo \u00e9 fortalecer o F\u00f3rum e aumentar seu n\u00edvel de representatividade\u201d, destacou.<\/p>\n<p>Entre as altera\u00e7\u00f5es, o novo regimento amplia as responsabilidades da Secretaria T\u00e9cnica do F\u00f3rum, que passa a ter toda a estrutura organizacional da SCS do MDIC. No organograma atual, o \u00f3rg\u00e3o integra um dos departamentos da secretaria, sem v\u00ednculo direto com o secret\u00e1rio.<\/p>\n<p>O f\u00f3rum tamb\u00e9m passa a ter como integrante a Frente Parlamentar Mista de Apoio \u00e0s Micro e Pequenas Empresas. Os demais integrantes s\u00e3o as entidades de apoio e de representa\u00e7\u00e3o nacional do segmento de MPEs, \u00f3rg\u00e3os governamentais, F\u00f3runs Regionais das MPEs e o Servi\u00e7o Brasileiro de Apoio \u00e0s Micro e Pequenas Empresas (Sebrae).<\/p>\n<p>A pr\u00f3xima reuni\u00e3o do F\u00f3rum Permanente das Microempresas e Empresas de Pequeno Porte tamb\u00e9m ser\u00e1 realizada em Bras\u00edlia, dia 2 de dezembro deste ano.<\/p>\n<p>Assessoria de Comunica\u00e7\u00e3o Social do MDIC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MEI &#8211; Os estados do Cear\u00e1, Esp\u00edrito Santo, Paran\u00e1, Rio Grande do Sul, Rond\u00f4nia e Santa Catarina ser\u00e3o inclu\u00eddos no Empreendedor Individual (EI), na primeira semana de setembro. O an\u00fancio foi feito secret\u00e1rio de Com\u00e9rcio e Servi\u00e7os (SCS) do Minist\u00e9rio do Desenvolvimento, Ind\u00fastria e Com\u00e9rcio Exterior (MDIC), Edson Lupatini, nesta quinta-feira (27\/8), em Bras\u00edlia, durante [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,7],"tags":[],"class_list":["post-10123","post","type-post","status-publish","format-standard","category-brasil","category-economia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/10123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=10123"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/10123\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=10123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=10123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=10123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}