{"id":10038,"date":"2009-08-28T18:29:09","date_gmt":"2009-08-28T22:29:09","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=10038"},"modified":"2009-09-14T14:49:53","modified_gmt":"2009-09-14T18:49:53","slug":"inscricao-no-concurso-publico-para-2-000-vagas-pmsp-comeca-em-0110","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/inscricao-no-concurso-publico-para-2-000-vagas-pmsp-comeca-em-0110\/10038","title":{"rendered":"Inscri\u00e7\u00e3o no Concurso P\u00fablico para 2.000 vagas PM\/SP come\u00e7a em 01\/10"},"content":{"rendered":"<p>A Pol\u00edcia Militar do Estado de S\u00e3o Paulo <strong>PM\/SP<\/strong> est\u00e1 com <strong>inscri\u00e7\u00f5es <\/strong>abertas para o preenchimento de 2.000 (dois mil) cargos de Soldado (masculino) atrav\u00e9s de <strong>concurso p\u00fablico<\/strong>. O sal\u00e1rio inicial m\u00ednimo de R$ 2.387,00 (dois mil, trezentos e oitenta e sete reais).\u00a0O Edital de Abertura do Concurso foi publicado no Di\u00e1rio Oficial do Estado (D.O.E) &#8211; N\u00ba 150, de 13 de agosto de 2009. Nele o candidato encontra todas as informa\u00e7\u00f5es sobre a realiza\u00e7\u00e3o do concurso. \u00c9 importante que todos leiam atentamente todo o edital.<\/p>\n<p>Duas altera\u00e7\u00f5es ocorreram em rela\u00e7\u00e3o ao edital de 2008.<\/p>\n<p>PRIMEIRA: O candidato escolher\u00e1 onde realizar\u00e1 as Provas de Escolaridade (Partes I e II), dentre 10 (dez) munic\u00edpios do Estado. S\u00e3o eles: S\u00e3o Paulo, Bauru, Campinas, Piracicaba, Presidente Prudente, Ribeir\u00e3o Preto, Santos, S\u00e3o Jos\u00e9 do Rio Preto, S\u00e3o Jos\u00e9 dos Campos e Sorocaba.<br \/>\nAs demais etapas ser\u00e3o realizadas exclusivamente na cidade de S\u00e3o Paulo.<\/p>\n<p>SEGUNDA: Na prova de condicionamento f\u00edsico o teste na barra fixa foi substitu\u00eddo pelo teste de apoio de frente sobre o solo com flex\u00e3o e extens\u00e3o de cotovelos.<\/p>\n<p>O concurso ser\u00e1 de Provas e T\u00edtulos, composto das seguintes etapas:<br \/>\na. Prova de Escolaridade (Partes I e II),<br \/>\nb. Prova de Condicionamento F\u00edsico,<br \/>\nc. Exames M\u00e9dicos,<br \/>\nd. Exames Psicol\u00f3gicos,<br \/>\ne. Investiga\u00e7\u00e3o Social,<br \/>\nf. An\u00e1lise de Documentos e T\u00edtulos.<br \/>\nREQUISITOS PARA INGRESSO<\/p>\n<p>a. ser brasileiro,<br \/>\nb. ter idade compreendida entre 18 (dezoito) e 30 (trinta) anos, na data da inscri\u00e7\u00e3o,<br \/>\nc. ter conclu\u00eddo o curso de ensino m\u00e9dio ou equivalente,<br \/>\nd. ter estatura m\u00ednima, descal\u00e7o e descoberto, de 1,65m (um metro e sessenta e cinco cent\u00edmetros),<br \/>\ne. estar em dia com as obriga\u00e7\u00f5es eleitorais e no pleno exerc\u00edcio dos direitos pol\u00edticos,<br \/>\nf. possuir documento militar que comprove ter prestado ou ter sido definitivamente liberado do Servi\u00e7o Militar inicial,<br \/>\ng. se funcion\u00e1rio p\u00fablico, n\u00e3o ter respondido a Processo Administrativo cujo fundamento o possa incompatibilizar com a fun\u00e7\u00e3o policial-militar,<br \/>\nh. n\u00e3o registrar antecedentes criminais,<\/p>\n<p>PROCEDIMENTOS PARA <strong>INSCRI\u00c7\u00c3O<\/strong><\/p>\n<p>Objetivando evitar \u00f4nus desnecess\u00e1rio, o candidato dever\u00e1 orientar-se no sentido de recolher o valor da <strong>inscri\u00e7\u00e3o<\/strong> somente ap\u00f3s tomar conhecimento de todos os requisitos exigidos para o Concurso.<br \/>\nAs inscri\u00e7\u00f5es dever\u00e3o ser realizadas somente via INTERNET, no per\u00edodo de 01 a 25 de setembro de 2009, por meio do site da Funda\u00e7\u00e3o <a href=\"http:\/\/www.vunesp.com.br\" target=\"_blank\">VUNESP.<\/a><br \/>\nO candidato dever\u00e1 preencher a Ficha de Inscri\u00e7\u00e3o de forma correta, optando para realizar em um dos munic\u00edpios descritos anteriormente.<br \/>\nO valor da inscri\u00e7\u00e3o ser\u00e1 de R$ 39,00 (trinta e nove reais) e poder\u00e1 ser paga em qualquer ag\u00eancia banc\u00e1ria.<\/p>\n<p>REDU\u00c7\u00c3O DO VALOR DA TAXA DE INSCRI\u00c7\u00c3O<\/p>\n<p>O candidato ter\u00e1 direito \u00e0 redu\u00e7\u00e3o de 50 do valor do pagamento da taxa de inscri\u00e7\u00e3o, nos termos da Lei Estadual n\u00ba 12.782, de 20 de dezembro de 2007, desde que cumpridos, cumulativamente, os seguintes requisitos:<br \/>\na. seja estudante, assim considerado aquele que se encontre regularmente matriculado em: uma das s\u00e9ries do ensino fundamental ou m\u00e9dio, curso pr\u00e9-vestibular ou curso superior, em n\u00edvel de gradua\u00e7\u00e3o ou p\u00f3s-gradua\u00e7\u00e3o,<br \/>\nb. receba remunera\u00e7\u00e3o mensal inferior a 2 (dois) sal\u00e1rios m\u00ednimos ou esteja desempregado.<br \/>\nA solicita\u00e7\u00e3o da redu\u00e7\u00e3o do valor da taxa de inscri\u00e7\u00e3o dever\u00e1 ser feita ANTERIORMENTE ao per\u00edodo de inscri\u00e7\u00e3o, das 10 horas de 17 de agosto de 2009 \u00e0s 23 horas e 59 minutos de 18 de agosto de 2009.<br \/>\nNo site , em \u201clink\u201d pr\u00f3prio do concurso, o candidato preenche o requerimento, imprime, anexando os documentos que comprovem sua situa\u00e7\u00e3o.<br \/>\nO prazo para entrega \u00e9 at\u00e9 21 de agosto de 2009, entre 08h30 e 17h00. Os documentos devem ser levados pessoalmente ou atrav\u00e9s de procura\u00e7\u00e3o, \u00e0 Divis\u00e3o de Sele\u00e7\u00e3o e Alistamento da Diretoria de Pessoal, na Avenida Cruzeiro do Sul, n\u00ba 260 \u2013 1\u00ba andar \u2013 sala 146, bairro Canind\u00e9, S\u00e3o Paulo-SP.<br \/>\nA resposta \u00e0 solicita\u00e7\u00e3o ser\u00e1 publicada no Di\u00e1rio Oficial a partir do dia 27 de agosto de 2009.<br \/>\nO candidato que tiver a solicita\u00e7\u00e3o deferida dever\u00e1 acessar novamente o \u201clink\u201d pr\u00f3prio na p\u00e1gina do concurso, digitar seu CPF e proceder \u00e0 efetiva\u00e7\u00e3o da inscri\u00e7\u00e3o com valor da taxa de inscri\u00e7\u00e3o reduzida, at\u00e9 o dia 25 de setembro de 2009. Caso contr\u00e1rio dever\u00e1 proceder da mesma forma e efetuar o pagamento com o valor da taxa de inscri\u00e7\u00e3o plena.<\/p>\n<p>Para melhor esclarecimento- segue abaixo tabela com o cronograma da inscri\u00e7\u00e3o:<br \/>\nDias 17 e 18 de agosto\u00a0,,,,-Solicita\u00e7\u00e3o da redu\u00e7\u00e3o do valor da taxa de inscri\u00e7\u00e3o<br \/>\nA partir de 27 de agosto\u00a0,,,,-Publica\u00e7\u00e3o das solicita\u00e7\u00f5es deferidas<br \/>\nDe 01 a 25 de setembro\u00a0,,,,-Inscri\u00e7\u00f5es para o concurso<\/p>\n<p>Maiores informa\u00e7\u00f5es: Disque PM 0800.555.190, Disque VUNESP 3874.6300 e o site da Funda\u00e7\u00e3o VUNESP &#8211; <a href=\"http:\/\/www.vunesp.com.brwww.vunesp.com.br%3c\/A\">.<\/a><\/p>\n<p>Assessoria de Imprensa &#8211;<strong> Inscri\u00e7\u00e3o <\/strong>no<strong> Concurso P\u00fablico <\/strong>para<strong> 2.000 vagas PM\/SP\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Militar do Estado de S\u00e3o Paulo PM\/SP est\u00e1 com inscri\u00e7\u00f5es abertas para o preenchimento de 2.000 (dois mil) cargos de Soldado (masculino) atrav\u00e9s de concurso p\u00fablico. O sal\u00e1rio inicial m\u00ednimo de R$ 2.387,00 (dois mil, trezentos e oitenta e sete reais).\u00a0O Edital de Abertura do Concurso foi publicado no Di\u00e1rio Oficial do Estado [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,352],"tags":[],"class_list":{"0":"post-10038","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"category-concursos","8":"entry","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/10038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=10038"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/10038\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=10038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=10038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=10038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}